{"id":18973,"date":"2013-03-06T14:01:18","date_gmt":"2013-03-06T13:01:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=18973"},"modified":"2023-01-17T13:16:53","modified_gmt":"2023-01-17T12:16:53","slug":"6993-successo-della-calabria-a-olio-capitale-2013","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/6993-successo-della-calabria-a-olio-capitale-2013\/","title":{"rendered":"Successo della Calabria a \u201cOlio Capitale 2013\u201d"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>TRIESTE<\/strong> &#8211; L\u2019Assessore regionale all\u2019Agricoltura Michele Trematerra, a conclusione della rassegna internazionale \u201cOlio Capitale 2013\u201d, dedicata all\u2019olio extra vergine<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">d&#8217;oliva, che si \u00e8 svolta dall\u2019 1 al 4 marzo alla Fiera di Trieste, si \u00e8 detto \u201centusiasta per il successo dell\u2019iniziativa che ha rappresentato un\u2019opportunit\u00e0 di incontro unica per gli addetti ai lavori, in grado di favorire lo scambio e la divulgazione, su larga scala, delle conoscenze inerenti il principe indiscusso della dieta mediterranea: l&#8217;olio extravergine d&#8217;oliva\u201d. \u201cOlio Capitale \u2013 ha spiegato l\u2019Assessore &#8211; \u00e8 la celebrazione dell&#8217;olio ai massimi livelli, dove i buyer internazionali incontrano il \u201cmercato\u201d e le novit\u00e0 che questo offre\u201d.<\/p>\n<p style=\"text-align: justify;\">Un\u2019edizione da record quella appena conclusa \u2013 \u00e8 scritto in una nota dell\u2019ufficio stampa della giunta regionale -, con oltre 10.000 partecipanti, che ha visto la Regione Calabria organizzare una serie di incontri divulgativi, a valere sulla misura 111 azione 3 del PSR Calabria 2007\/2013, che hanno fatto registrare sempre il tutto esaurito, non solo da parte degli addetti ai lavori, ma anche di semplici visitatori e curiosi interessati ad avvicinarsi al mondo dell\u2019olio d\u2019oliva di qualit\u00e0. Molteplici e sempre stimolanti i temi trattati nel corso dei seminari, tra i quali&nbsp; \u201cCarolea: il trait d\u2019union dell\u2019olivicoltura calabrese\u201d&nbsp; e quelli che hanno visto protagonisti l\u2019oleologo internazionale Luigi Caricato ed il giornalista enogastronomico Maurizio Pescari, che hanno approfondito varie tematiche, in particolare quelle inerenti gli aspetti commerciali di&nbsp; marketing aziendale sia a livello nazionale che internazionale.<\/p>\n<p style=\"text-align: justify;\">Nel corso dei seminari si sono&nbsp; affrontati inoltre le particolari peculiarit\u00e0 dell\u2019olio calabrese, che negli ultimi anni dal punto di vista qualitativo viene sempre di pi\u00f9 apprezzato dai consumatori . \u201cUn successo oltre ogni aspettativa \u2013 ha continuato l\u2019Assessore &#8211; \u00e8 stato inoltre il workshop conclusivo organizzato sempre dalla Regione Calabria, tenutosi nell\u2019area della scuola di cucina, che ha visto la partecipazione al dibattito, ancora una volta, degli esperti Luigi Caricato e&nbsp; Maurizio Pescari, del ristoratore Francesco Saliceti e del Dirigente Generale del Dipartimento Agricoltura Giuseppe Zimbalatti, al quale \u00e8 seguito una degustazione guidata di tutti gli oli calabresi&nbsp; presenti in fiera. Continua cos\u00ec, &#8211; ha concluso&nbsp; Trematerra &#8211; il percorso di valorizzazione intrapreso per l\u2019olio extravergine di oliva calabrese, incentrato anche sulla sensibilizzazione dei vari protagonisti della filiera.<\/p>\n<p style=\"text-align: justify;\">L\u2019auspicio \u00e8 che questa ennesima tappa di \u201cpromozione\u201d, possa ulteriormente avvicinare alla consacrazione definitiva l\u2019olio extravergine di Calabria in quanto prodotto di \u201ceccellenza\u201d, giusto coronamento del lavoro portato avanti in questi anni dall\u2019Assessorato all\u2019Agricoltura, anche grazie all\u2019importanza attribuita a questo settore dalla Giunta guidata dal Presidente Scopelliti\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRIESTE &#8211; L\u2019Assessore regionale all\u2019Agricoltura Michele Trematerra, a conclusione della rassegna internazionale \u201cOlio Capitale 2013\u201d, dedicata all\u2019olio extra vergine<\/p>\n","protected":false},"author":22,"featured_media":18974,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-18973","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18973","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=18973"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/18973\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/18974"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=18973"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=18973"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=18973"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}