{"id":19025,"date":"2013-03-07T11:06:40","date_gmt":"2013-03-07T10:06:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19025"},"modified":"2023-01-17T13:16:57","modified_gmt":"2023-01-17T12:16:57","slug":"7019-soccorsa-donna-priva-di-sensi-al-volante","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7019-soccorsa-donna-priva-di-sensi-al-volante\/","title":{"rendered":"Soccorsa donna priva di sensi al volante"},"content":{"rendered":"<p><strong>LAMEZIA TERME<\/strong> &#8211; Durante un servizio di controllo sul territorio, gli Agenti del Commissariato di Polizia di Lamezia Terme, hanno soccorso una donna ritrovata priva di sensi al volante della propria auto, probabilmente a<\/p>\n<p>  <!--more-->  <\/p>\n<p>causa di un malore. Il soccorso \u00e8 avvenuto nei pressi dello stadio Carlei. &nbsp;Accertato pertanto lo stato di incoscienza i poliziotti hanno allertato gli operatori del 118 e al fine di velocizzare i \u00ecsoccorsi dei sanitari hanno aperto le portiere dell&#8217;autovettura bloccate dal sistema di chiusura centralizzato. Dopo vari tentativi, gli agenti, con un fil di ferro rinvenuto in prossimita&#8217; dell&#8217;autovettura, hanno disinserito disinserire il sistema di chiusura approfittando del vetro anteriore rimasto leggermente aperto. In attesa di personale medico hanno provveduto ad avvisare i familiari della ragazza. Poco dopo e&#8217; arrivatoa sul posto personale del 118che l&#8217;aha trasportata in ospedale.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LAMEZIA TERME &#8211; Durante un servizio di controllo sul territorio, gli Agenti del Commissariato di Polizia di Lamezia Terme, hanno soccorso una donna ritrovata priva di sensi al volante della propria auto, probabilmente a<\/p>\n","protected":false},"author":22,"featured_media":19026,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-19025","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19025"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19025\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19026"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}