{"id":19027,"date":"2013-03-07T11:11:36","date_gmt":"2013-03-07T10:11:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19027"},"modified":"2023-01-17T13:16:57","modified_gmt":"2023-01-17T12:16:57","slug":"7020-scardinati-i-vertici-del-clan-mancuso-zu-luni-ora-comanda-la-massoneria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7020-scardinati-i-vertici-del-clan-mancuso-zu-luni-ora-comanda-la-massoneria\/","title":{"rendered":"Scardinati i vertici del clan Mancuso. &#8216;Zu Luni&#8217;: \u201cOra comanda la massoneria\u201d"},"content":{"rendered":"<p><span style=\"font-size: 12px; line-height: 1;\">CATANZARO \u2013 Associazione a delinquere di stampo mafioso. <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Ben 24 esponenti della cosca Mancuso di Limbadi, ritenuta dalle forze dell&#8217;ordine tra le pi\u00f9 pericolose, sono stati tratti in arresto stamane a seguito di un&#8217;operazione congiunta di polizia, carabinieri e guardia di finanza. A finire in manette i vertici storici della cosca, noti imprenditori vibonesi operanti nei settori siderurgici e dei servizi turistici e finanche un funzionario dell&#8217;Ufficio tecnico del Comune di Tropea. La Guardia di Finanza di Trieste ha affiancato nell&#8217;operazione il Servizio centrale operativo della Polizia di Stato grazie al quale \u00e8 stata portata a termine l&#8217;operazione con l&#8217;aiuto della Squadra Mobile di Catanzaro, il Ros Carabinieri e il Gico della Guardia di Finanza di Catanzaro. A carico degli arrestati, nella circostanza, sono stati&nbsp;eseguiti anche numerosi sequestri di beni e aziende.<\/p>\n<p>&nbsp;<\/p>\n<p align=\"JUSTIFY\" style=\"margin-bottom: 0cm; text-align: justify;\">&nbsp;<\/p>\n<p align=\"JUSTIFY\" style=\"margin-bottom: 0cm;\"><strong>\u201cZu Luni\u201d spiega il rapporto tra &#8216;Ndrangheta, massoneria e Forza Italia<\/strong><\/p>\n<p align=\"JUSTIFY\" style=\"margin-bottom: 0cm; text-align: justify;\">&#8220;Se a me serve una visita specialistica io non ho alcun bisogno di prenotazione&#8221;. E&#8217; una delle frasi pronunciate dal capo della cosca di Limbadi per descrivere il potere dell&#8217;appartenenza alla criminalit\u00e0 da Pantaleone Mancuso, che gli investigatori hanno captato nel corso della lunga indagine. Durante le conversazioni intercettate il boss, dunque, si vanta dei suoi rapporti e del suo &#8220;prestigio&#8221; Criminale. Frasi ritenute di altissimo valore investigativo, con cui Mancuso descrive per circa un&#8217;ora cosa sia la &#8216;ndrangheta e quali siano i rapporti con la massoneria. <strong>&#8220;Il mondo cambia e bisogna cambiare tutte cose!&#8230; Oggi la chiamiamo Massoneria, Domani la chiamiamo P4, P6, P9<\/strong>?&#8221;. Cos\u00ec Pantaleone Mancuso, detto &#8216;Zu Luni&#8217;, in una lunga conversazione spiega dettagliatamente com&#8217;\u00e8 cambiata nel corso del tempo la fisionomia della &#8216;ndrangheta. &#8220;La &#8216;ndrangheta non esiste pi\u00f9! &#8211; afferma Pantaleone Mancuso &#8211; Una volta, a Limbadi, a Nicotera, a Rosarno, c&#8217;era la &#8216;ndrangheta!&#8230; La &#8216;ndrangheta fa parte della massoneria!&#8230; Diciamo \u00e8 sotto della massoneria, per\u00f2 hanno le stesse regole e le stesse cose. Ora cosa c&#8217;\u00e8 piu&#8217;?&#8230; Ora \u00e8 rimasta la massoneria e quei quattro storti che ancora credono alla &#8216;ndrangheta!&#8230; Una volta era dei benestanti la &#8216;ndrangheta!&#8230; Dopo gliel&#8217;hanno lasciata ai poveracci, agli zappatori e hanno fatto la massoneria!&#8230; Le regole quelle sono!&#8230; Come ce l&#8217;ha la massoneria ce l&#8217;ha quella!&#8230; Perch\u00e8 la vera &#8216;ndrangheta non \u00e8 quella che dicono loro, perch\u00e8 lo &#8216;ndranghetista non \u00e8 che va a fare quello che dicono loro. Perch\u00e8, una volta, adesso sono tutti giovanotti che vanno, vanno a ruota libera, sono drogati! Delinquenza comune!&#8230; Lo &#8216;ndranghetista non voleva fare droga, non faceva mai una lite, come non voleva non faceva droga, adesso sono quattro drogati!&#8230; Pare che uno che faceva il magnaccio, pare che poteva stare nella &#8216;Rota&#8217;&#8230; O che picchiava la moglie o che andava ad ubriacarsi non doveva entrare nemmeno nelle cantine lo &#8216;ndranghetista perch\u00e8 c&#8217;era il &#8216;Mastro di giornata&#8217; (carica tipica esistente in seno ad ogni &#8216;ndrina, la cui esistenza \u00e8 stata accertata in innumerevoli procedimenti penali, ndr) che girava nel paese e se ti vedeva che entravi nella cantina o che bevevi vino &#8216;nsaccagnate&#8217; (botte, ndr)&#8221;. &#8220;Ancora con la &#8216;ndrangheta sono rimasti! &#8211; insiste ancora Mancuso -&#8230; E&#8217; finita!&#8230; Bisogna fare come per dire c&#8217;era la &#8216;democrazia&#8217; \u00e8 caduta la &#8216;democrazia&#8217; e hanno fatto un altro partito Forza Italia, &#8216;Forza cose&#8217;, Bisogna modernizzarsi!&#8230; Non stare con le vecchie regole!\u201d&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><strong>Dal Friuli a Limbadi un fiume di denaro<\/strong><\/p>\n<p style=\"text-align: justify;\">Sono tre i filoni di inchiesta che sono sfociati nelle 24 ordinanze di fermo emesse dalla Direzione distrettuale antimafia di Catanzaro. Tutti confluiscono in un unico provvedimento che ha svelato gli interessi criminali con ramificazioni in tutte le province calabresi e fino a Trieste. Nello specifico, la squadra Mobile di Catanzaro, ha chiuso il cerchio intorno a dieci persone: Giovanni Mancuso, 72 anni, figura carismatica, e Antonio Mancuso, 75 anni. Sarebbero stati loro secondo gli inquirenti a guidare i prestiti <strong>usurari che costituivano il reinvestimento di capitali riconducibili alla cosca. In alcune circostanze per la restituzione degli interessi si mettevano in atto anche gravi ritorsioni fino al caso in cui una delle vittime \u00e8 stata sequestrata e minacciata con l&#8217;uso delle armi. I tassi usurai applicati dagli esponenti della cosca avrebbero raggiunto, in alcune circostanze, anche il 200%.<\/strong> Nel provvedimento della guardia di finanza di Vibo Valentia e Trieste, invece, sono stati sequestrati beni per 35 milioni di euro con il fermo di dieci persone e, complessivamente, la denuncia di 76 soggetti. Dopo alcuni approfondimenti bancari avviati in Friuli Venezia Giulia \u00e8 stato possibile ricondurre l&#8217;attivit\u00e0 agli esponenti calabresi della cosca Mancuso, fino a ricostruire gli interessi criminali con estorsioni, usura e danneggiamenti. Tutto questo con il clan che era riuscito a controllare il settore economico della distribuzione e commercializzazione all&#8217;ingrosso di generi alimentari e nel settore turistico immobiliare. Fra i principali responsabili di questa parte dell&#8217;operazione, la Guardia di Finanza ha individuato Agostino Papaianni che si occupava di occultare le risorse economiche avvalendosi, secondo le accuse, di diversi prestanomi a cui erano stati intestati beni immobili e mobili. Tra i beni sequestrati figurano due societ\u00e0; un distributore di carburante con autolavaggio e bar; un supermercato; una concessionaria di autovetture; un bar nella piazza di Tropea; un panificio industriale e numerosi conti correnti bancari. A questo si aggiunge un villaggio turistico, formalmente intestato ad un prestanome di origine nordafricana, composto da decine di appartamenti, piscina, market, due ristoranti, area camper e stabilimento balneare. Infine, il terzo filone dell&#8217;inchiesta, seguito dai carabinieri del Ros, che ha permesso di fermare Pantaleone Mancuso, ritenuto il capo della cosca, e il figlio Giuseppe Mancuso, 35 anni. Secondo i militari dell&#8217;Arma, i due avrebbero messo in piedi un qualificato circuito criminale nelle province di Vibo Valentia, Reggio Calabria e Crotone, con ramificazioni nel nord Italia. Il figlio Giuseppe avrebbe assunto la reggenza del clan durante la detenzione del padre, con i carabinieri che sono riusciti a ricostruire anche modalit\u00e0 alternative alla fittizia intestazione di beni, attraverso le quali il sodalizio avrebbe acquisito la gestione e il controllo di attivit\u00e0 imprenditoriali. Beni, aziende e disponibilit\u00e0 finanziarie, per un valore di 35 milioni di euro, sono stati sequestrati nell&#8217;ambito dell&#8217;operazione che ha scardinato i vertici storici della cosca tra le pi\u00f9 temute nel panorama della criminalit\u00e0 organizzata, operativa ben oltre i confini della Calabria<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><strong>I nomi<\/strong><\/p>\n<p><p style=\"text-align: justify;\">Le ordinanze di custodia cautelare sono state emesse tutte con l&#8217;accusa, a vario titolo, di associazione mafiosa, ad esclusione del provvedimento a carico di Antonio Prestia. Gli arrestati sono: Pasquale Mancuso, 66 anni; Giovanni Mancuso, 72; Giuseppe Mancuso, 36; Antonio Maccarone, 34; Antonio Cuturello, 23; Giovanni D&#8217;Aloi, 47; Giuseppe Costantino, 47; Fabio Costantino, 36; Zbigniew Damian Fialek, 36; Antonio Pantano, 56; Francesco Tavella, 55; Orazio Cicerone, 40; Mario De Rito, 39; Antonino Castagna, 63; Giuseppe Raguseo, 35; Agostino Papaianni, 62; Leonardo Cuppari, 39; Bruno Marano, 32; Antonio Mamone, 45; Antonino Scrugli, 37; Gabriele Bombai, 43; Salvatore Accorinti, 39; Giovanni Antonio Paparatto, 40; Antonio Prestia, 45.<\/p>\n<p>&nbsp;<\/p>\n<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO \u2013 Associazione a delinquere di stampo mafioso.<\/p>\n","protected":false},"author":22,"featured_media":19028,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-19027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19027"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19027\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19028"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}