{"id":193958,"date":"2023-02-22T20:08:34","date_gmt":"2023-02-22T19:08:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=193958"},"modified":"2023-02-22T20:09:08","modified_gmt":"2023-02-22T19:09:08","slug":"cosenza-reggina-studenti-e-scuole-calcio-della-provincia-gratis-in-curva-nord-e-sud","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-reggina-studenti-e-scuole-calcio-della-provincia-gratis-in-curva-nord-e-sud\/","title":{"rendered":"Cosenza-Reggina, studenti e scuole calcio della provincia gratis in curva Nord e Sud"},"content":{"rendered":"<p>COSENZA &#8211; Iniziativa del Cosenza Cosenza Calcio in vista del derby di marted\u00ec prossimo contro la Reggia. La societ\u00e0 rossoblu ha deciso di <strong>aprire (gratis) la porte dello stadio &#8220;San Vito Gigi Marulla&#8221;<\/strong> ai <strong>ragazzi delle scuole e delle scuole calcio della provincia<\/strong>. Per la gara tra Cosenza e Reggina in programma alle ore 20:30 di marted\u00ec 28 febbraio, gli istituti scolastici e le scuole calcio potranno aderire all\u2019iniziativa consentendo ai propri iscritti <strong>di et\u00e0 inferiore ai 18 anni<\/strong> di a<strong>ccedere gratuitamente ai settori Curva Sud Bergamini e Curva Nord Massimo Catena.<\/strong><\/p>\n<p>Gli enti d<strong>ovranno inviare il modulo in formato excel<\/strong> (<a href=\"http:\/\/www.ilcosenza.it\/2023\/02\/22\/invito-alle-scuole-e-alle-scuole-calcio-della-provincia\/\" target=\"_blank\" rel=\"noopener\">disponibili a questa pagina sul sityo ufficiale<\/a>) compilato in ogni spazio, indicando il settore prescelto, nome, cognome, luogo e data di nascita, provincia di nascita, provincia di residenza e i medesimi dati per un accompagnatore, che deve essere indicato per ogni dieci minori presenti nell\u2019elenco.<\/p>\n<p>Il modulo in formato excel dovr\u00e0 essere i<strong>noltrato entro e non oltre le ore 13:00 di sabato 25 febbraio<\/strong> all\u2019indirizzo <a href=\"mailto:biglietteria@nuovacosenzacalcio.it\">biglietteria@nuovacosenzacalcio.it<\/a>, le richieste prevenute successivamente non potranno essere prese in considerazione. Non sar\u00e0 possibile emettere tagliandi per chi \u00e8 in possesso di un abbonamento valido per la stagione\u00a0in\u00a0corso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Iniziativa del Cosenza Cosenza Calcio in vista del derby di marted\u00ec prossimo contro la Reggia. La societ\u00e0 rossoblu ha deciso di aprire (gratis) la porte dello stadio &#8220;San Vito Gigi Marulla&#8221; ai ragazzi delle scuole e delle scuole calcio della provincia. Per la gara tra Cosenza e Reggina in programma alle ore 20:30 [&hellip;]<\/p>\n","protected":false},"author":24,"featured_media":191689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-193958","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/193958","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=193958"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/193958\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/191689"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=193958"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=193958"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=193958"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}