{"id":19427,"date":"2013-03-13T16:55:24","date_gmt":"2013-03-13T15:55:24","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19427"},"modified":"2023-01-17T13:17:18","modified_gmt":"2023-01-17T12:17:18","slug":"7225-omaggio-della-provincia-al-poeta-ciccio-de-marco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7225-omaggio-della-provincia-al-poeta-ciccio-de-marco\/","title":{"rendered":"Omaggio della Provincia al poeta Ciccio De Marco"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA<\/strong> &#8211; &nbsp;La Provincia, ha organizzato per domani, Gioved\u00ec 14 marzo, &nbsp;un omaggio al&nbsp;poeta cosentino Ciccio De Marco, recentemente scomparso.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">&nbsp;L&#8217; appuntamento sar\u00e0&nbsp;alle ore 17,00, nella Sala degli Specchi del Palazzo di piazza XV marzo, con &nbsp;l&#8217;assessore alla Cultura Maria Francesca Corigliano che &nbsp;ricorder\u00e0 il poeta autore di tante liriche come di &nbsp;testi teatrali.&nbsp;<br \/>La manifestazione, che vede &nbsp;la collaborazione dell&#8217;Associazione ex Alunni del Liceo &#8220;Telesio&#8221; di Cosenza, del Comitato di Cosenza della Societ\u00e0 &#8220;Dante Alighieri&#8221; e del Laboratorio Culturale &#8220;Cosenza che vive\u201d prevede &nbsp;anche un recital di poesie con l&#8217;attore Totonno Chiappetta ed il Maestro Renato Sabato.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &nbsp;La Provincia, ha organizzato per domani, Gioved\u00ec 14 marzo, &nbsp;un omaggio al&nbsp;poeta cosentino Ciccio De Marco, recentemente scomparso.<\/p>\n","protected":false},"author":22,"featured_media":19428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-19427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19427"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19428"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}