{"id":19467,"date":"2013-03-14T13:09:53","date_gmt":"2013-03-14T12:09:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19467"},"modified":"2023-01-17T13:17:21","modified_gmt":"2023-01-17T12:17:21","slug":"7250-firmato-accordo-programmazione-pisl","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7250-firmato-accordo-programmazione-pisl\/","title":{"rendered":"Firmato accordo programmazione Pisl"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>VIBO VALENTIA<\/strong> &#8211; &nbsp;L&#8217;Assessore al Bilancio e alla Programmazione Nazionale e Comunitaria, Giacomo Mancini, questa mattina, a Vibo, ha siglato l&#8217;accordo<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">di programmazione negoziata con i capofila dei Pisl (Progetti Integrati per lo Sviluppo Locale) ammessi a finanziamento nel vibonese. &#8220;Si completa, dunque, &#8211; si legge in una nota della Regione &#8211; una prima fase importante per l&#8217;iter della progettazione integrata: grazie a questo accordo &#8211; che fa seguito a quelli stipulati nelle scorse settimane a Cosenza, Reggio Calabria, Catanzaro e Crotone &#8211; la Calabria e&#8217; pronta a ricevere circa 350milioni di euro di fondi europei finanziati dall&#8217;amministrazione regionale, per 72 Pisl complessivi.<\/p>\n<p style=\"text-align: justify;\">Di questi, circa 42 milioni di euro spettano ai comuni della provincia di Vibo Valentia per i quali sono stati ammessi a finanziamento 8 Pisl. A firmare l&#8217;accordo con l&#8217;Assessore Mancini, i capofila: Mongiana, Vibo Valentia, Tropea, Spilinga e Soriano Calabro. In seguito a questa firma, infatti, la Regione e i capofila sottoscrittori assumono congiuntamente precisi obblighi rispetto all&#8217;utilizzo delle risorse e alla realizzazione degli interventi, secondo quanto stabilito dai 13 articoli di cui l&#8217;atto amministrativo si compone&#8221;. &#8220;Oggi e&#8217; un momento molto importante anche per Vibo Valentia, per la sua comunita&#8217;, per la sua provincia &#8211; ha dichiarato l&#8217;Assessore Mancini -. Sigliamo tra Regione e capofila l&#8217;accordo di programmazione negoziata per realizzare i Pisl.<\/p>\n<p style=\"text-align: justify;\">L&#8217;amministrazione regionale, guidata dal Governatore Scopelliti, ha stanziato per questo territorio 42milioni di euro, suddivisi in diversi interventi che riguardano in particolare il &#8220;Turismo&#8221;, con circa 24milioni di euro, che andranno a vantaggio del territorio di Vibo Valentia, delle Alte Serre Vibonesi e di Tropea, ai quasi 9milioni di euro per i &#8220;Sistemi Produttivi&#8221; che fanno capo a Spilinga e altre risorse indirizzate ai &#8220;Borghi d&#8217;eccellenza&#8221; e per il miglioramento della &#8220;Qualita&#8217; della vita&#8221; di questo territorio&#8221;.<\/p>\n<p style=\"text-align: justify;\">&#8220;Abbiamo fatto un lavoro importante, sacramentato da questa firma che fa scaturire degli impegni giuridici decisivi. Da oggi, infatti, i capofila hanno la possibilita&#8217; di spendere queste risorse &#8211; ha spiegato l&#8217;Assessore &#8211; quindi l&#8217;invito che noi rivolgiamo agli amministratori e&#8217; di fare bene e rapidamente perche&#8217; la Commissione Europea ci impone di portare a compimento le opere in tempi stretti. Noi abbiamo recuperato un grave ritardo rispetto al passato. Il territorio ha elaborato dei progetti che sono stati valutati e ammessi a finanziamento.<\/p>\n<p style=\"text-align: justify;\">Ora con questa firma mettiamo i territori nelle condizioni di partire con i bandi e, di conseguenza, con la realizzazione dei progetti. Riusciremo, ne sono convinto, &#8211; ha concluso Mancini &#8211; a tagliare insieme questo altro importante traguardo&#8221;. Gli investimenti riguarderanno le tipologie di Pisl: &#8220;Qualita&#8217; della vita&#8221;, &#8220;Mobilita&#8217; intercomunale&#8221;, &#8220;Sistemi Turistici&#8221;, &#8220;Sistemi produttivi&#8221; e &#8220;Borghi d&#8217;eccellenza&#8221;. Tocca ora alle amministrazioni locali avviare i bandi di gara e rispettare due improrogabili scadenze: entro il 31 dicembre di quest&#8217;anno si dovra&#8217; dare vita agli impegni giuridicamente vincolanti ed entro il 31 dicembre del 2015 dovranno essere spese tutte le risorse.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; &nbsp;L&#8217;Assessore al Bilancio e alla Programmazione Nazionale e Comunitaria, Giacomo Mancini, questa mattina, a Vibo, ha siglato l&#8217;accordo<\/p>\n","protected":false},"author":22,"featured_media":19468,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-19467","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19467"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19468"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}