{"id":19499,"date":"2013-03-15T08:04:06","date_gmt":"2013-03-15T07:04:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19499"},"modified":"2023-01-17T13:17:22","modified_gmt":"2023-01-17T12:17:22","slug":"7266-stipendi-arretrati-lassessore-fedele-tranquillizza-gli-autisti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7266-stipendi-arretrati-lassessore-fedele-tranquillizza-gli-autisti\/","title":{"rendered":"Stipendi arretrati, l&#8217;assessore Fedele tranquillizza gli autisti"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><p style=\"text-align: justify;\">CATANZARO &#8211; A fine mese il bonifico non arriva, ma l&#8217;assessore di Scopelliti invita ad avere pazienza.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">L&#8217;assessore regionale ai Trasporti Luigi Fedele interviene &#8211; attraverso una nota &#8211; in merito alla questione sollevata dalle associazioni di categoria Anav e Asstra sull&#8217;erogazione delle spettanze pregresse. &#8220;Consapevole delle difficolt\u00e0 manifestate dalle aziende di trasporto pubblico locale e dalle loro associazioni &#8211; dichiara Fedele &#8211; posso assicurare che \u00e8 gi\u00e0 stato avviato l&#8217;iter per consentire l&#8217;immediata erogazione delle spettanze pregresse. Il ritardo con cui ci muoviamo deriva dalla mancata assunzione, ad oggi, del decreto del Presidente del Consiglio dei Ministri di ripartizione del fondo unico dei trasporti, che per legge sarebbe dovuta avvenire entro il 31 gennaio. In merito, poi, al reperimento delle risorse necessarie per assicurare i servizi dell&#8217;anno corrente &#8211; assicura l&#8217;assessore ai trasporti &#8211; \u00e8 gi\u00e0 stata individuata una quota aggiuntiva del fondo nazionale trasporti e nel prosieguo mi far\u00f2 garante, in prima persona, affinch\u00e8 le risorse mancanti siano recuperate dal bilancio regionale. L&#8217;amministrazione regionale, guidata dal Presidente Scopelliti, in questo senso, non ha mai lesinato attenzioni a questo settore cosi&#8217; importante per lo sviluppo della Calabria. Allo stesso tempo, pero&#8217;, chiedo alle aziende di partecipare attivamente e collaborare al processo di riorganizzazione ed efficientamento del sistema sia in termini di rimodulazione dei servizi sia mediante l&#8217;installazione di sistemi satellitari di controllo della percorrenza e di informazione in tempo reale all&#8217;utenza&#8221;. Insomma la burocrazia si muove, ma le tempistiche sono incerte. Agli operatori del settore trasporti non resta che aspettare. O protestare.<\/p>\n<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; CATANZARO &#8211; A fine mese il bonifico non arriva, ma l&#8217;assessore di Scopelliti invita ad avere pazienza.<\/p>\n","protected":false},"author":22,"featured_media":19500,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-19499","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19499","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19499"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19499\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19500"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19499"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19499"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19499"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}