{"id":19515,"date":"2013-03-15T10:22:41","date_gmt":"2013-03-15T09:22:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19515"},"modified":"2023-01-17T13:17:23","modified_gmt":"2023-01-17T12:17:23","slug":"7275-sorpresi-mentre-svaligiavano-un-bar-del-centro-arrestato-un-minorenne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7275-sorpresi-mentre-svaligiavano-un-bar-del-centro-arrestato-un-minorenne\/","title":{"rendered":"Sorpresi mentre svaligiavano un bar del centro. Arrestato un minorenne"},"content":{"rendered":"<p>SOVERATO &#8211; Un minorenne incensurato e un ventenne sono finiti in manette.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">I due sono stati colti in flagranza di reato mentre stavano svaligiando un bar di Soverato, che aveva subito gia&#8217; tre furti, ma sono stati sorpresi ed arrestati dai carabinieri della locale. &nbsp;Pietronicola Cosentino, 25 anni, gi\u00e0 noto alle forze dell&#8217;ordine, e il diciassettenne A.G., entrambi residenti a Guardavalle sono stati immediatament denunciati. I militari dell&#8217;Arma, diretti dal capitano Saverio Sica, avevano raddoppiato i servizi notturni, dopo una serie di denunce per furti in abitazioni private ed esercizi commerciali. Fino a quando, l&#8217;altra notte, due pattuglie hanno notato movimenti sospetti nei pressi del bar. Una persona, intorno alle 4 di notte, si \u00e8 affacciata dall&#8217;esercizio che era chiuso, e questo ha insospettito i militari. In quattro hanno fatto irruzione nel locale, scoprendo che i due giovani si erano nascosti in bagno. Nell&#8217;esercizio c&#8217;era una busta con dentro monete da 1 e 2 euro per un totale di 1.800 euro. Soldi che erano nelle slot machine e negli altri giochi elettronici presenti nel bar-sala giochi. Il maggiorenne \u00e8 stato posto agli arresti domiciliari, quindi, al termine del processo per direttissima, \u00e8 stato disposto l&#8217;obbligo di firma per due giorni a settimana; per il minorenne \u00e8 scattato l&#8217;accompagnamento presso il centro di accoglienza minorile di Catanzaro, dove si trova in attesa della decisione del magistrato. I carabinieri hanno anche provveduto a sequestrare diversi arnesi da scasso trovati ai due giovani. Nel corso di una conferenza stampa che si e&#8217; svolta nella Compagnia di Soverato, il capitano Sica ha sottolineato: &#8220;I reati predatori lasciano il segno sui cittadini, anche perch\u00e8 &#8211; ha spiegato &#8211; in alcuni casi \u00e8 stata invasa anche l&#8217;intimit\u00e0 familiare con furti nelle abitazioni. Per questo abbiamo predisposto turni raddoppiati con l&#8217;obiettivo di interrompere subito queste azioni illegali. L&#8217;unica richiesta che avanziamo ai cittadini &#8211; ha concluso &#8211; \u00e8 quella di chiamare il 112 ogni qual volta si dovessero notare movimenti sospetti o sentire rumori particolari&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>SOVERATO &#8211; Un minorenne incensurato e un ventenne sono finiti in manette.<\/p>\n","protected":false},"author":22,"featured_media":19516,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-19515","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19515","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19515"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19515\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19516"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19515"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19515"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19515"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}