{"id":19517,"date":"2013-03-15T22:00:00","date_gmt":"2013-03-15T21:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19517"},"modified":"2023-01-17T13:17:23","modified_gmt":"2023-01-17T12:17:23","slug":"7276-oncologia-al-via-settimana-di-controlli-preventivi-gratuiti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7276-oncologia-al-via-settimana-di-controlli-preventivi-gratuiti\/","title":{"rendered":"Oncologia: al via settimana di controlli preventivi gratuiti"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><span style=\"font-size: 12px; line-height: 1;\">CATANZARO &#8211; Prevenire per curare.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p><span style=\"font-size: 12px; line-height: 1;\">A partire da oggi sino al 24 marzo si terr\u00e0 la XII edizione della Settimana nazionale per la prevenzione oncologica, uno dei principali appuntamenti della Lega Italiana per la Lotta contro i Tumori. &#8220;In linea con lo spirito e gli obiettivi di questa iniziativa &#8211; si legge in una nota &#8211; , la Sezione Lilt di Catanzaro, come ogni anno sar\u00e0 presente in piazza e pi\u00f9 precisamente giorno 19 marzo in onore anche della festa del pap\u00e0, allestir\u00e0 il suo banchetto informativo con la distribuzione di una bottiglia di olio extra vergine di oliva &#8211; in cambio di un modesto contributo &#8211; presso il proprio ambulatorio sito in via Paparo a Catanzaro. Durante l&#8217;arco della mattinata dalle ore 8.30 alle ore 11, sara&#8217; attivo, gratuitamente presso lo stesso ambulatorio, il servizio di prelievo del sangue per il controllo del PSA, finalizzato alla prevenzione del carcinoma prostatico. Un infermiere specializzato sar\u00e0 a disposizione di tutti coloro che, dai 50 anni in su, pap\u00e0 e non, vorranno sottoporsi al prelievo a tutela della propria salute e con l&#8217;intento di intraprendere un percorso di prevenzione&#8221;. Il Presidente della Sezione Lilt di Catanzaro, Concetta Stanizzi, ricorda che &#8220;il testimonial unico della manifestazione quest&#8217;anno \u00e8 l&#8217;olio extra vergine d&#8217;oliva, un alleato indispensabile per la nostra salute&#8221; e sottolinea altres\u00ec che la settimana nazionale per la prevenzione oncologica &#8220;nasce per informare che pi\u00f9 di un terzo dei tumori non si svilupperebbe se mangiassimo in modo sano e corretto&#8221;.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; CATANZARO &#8211; Prevenire per curare.<\/p>\n","protected":false},"author":22,"featured_media":19518,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-19517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19517"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19517\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19518"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}