{"id":19543,"date":"2013-03-15T14:04:05","date_gmt":"2013-03-15T13:04:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19543"},"modified":"2023-01-17T13:17:25","modified_gmt":"2023-01-17T12:17:25","slug":"7289-muore-bambino-di-5-anni-in-una-palestra","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7289-muore-bambino-di-5-anni-in-una-palestra\/","title":{"rendered":"Muore bambino di 5 anni in una palestra"},"content":{"rendered":"<p><p><strong>SALERNO<\/strong> &#8211; Tragica sorte di dolore e casualit\u00e0 successa in una palestra di Altavilla Silentina (Salerno) dove un bambino, di soli 5 anni, durante un allenamento di avviamento allo judo, si \u00e8 accasciato a terra, morto. I genitori,<\/p>\n<p>  <!--more-->  <\/p>\n<p>che lo avevano accompagnato, si trovavano nella palestra al momento dell&#8217;accaduto. Inutili gli interventi. Sul posto sono giunti i Carabinieri della Compagnia di Eboli (Salerno). La Procura di Salerno ha disposto l&#8217;autopsia. I genitori, amici e conoscenti sono scioccati.<\/p>\n<p>&nbsp;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SALERNO &#8211; Tragica sorte di dolore e casualit\u00e0 successa in una palestra di Altavilla Silentina (Salerno) dove un bambino, di soli 5 anni, durante un allenamento di avviamento allo judo, si \u00e8 accasciato a terra, morto. I genitori,<\/p>\n","protected":false},"author":22,"featured_media":19544,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-19543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19543"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19544"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}