{"id":19569,"date":"2013-03-15T15:51:41","date_gmt":"2013-03-15T14:51:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19569"},"modified":"2023-01-17T13:17:26","modified_gmt":"2023-01-17T12:17:26","slug":"7302-disoccupati-in-citta-sono-180-in-meno-rispetto-al-2012","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7302-disoccupati-in-citta-sono-180-in-meno-rispetto-al-2012\/","title":{"rendered":"Disoccupati in citt\u00e0, sono 180 in meno rispetto al 2012"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA \u2013 Dati positivi sul fronte occupazionale.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Nonostante il numero di disoccupati in citt\u00e0 si attesti oltre le 12.500 unit\u00e0 la tendenza del mercato del lavoro a Cosenza pare stia fornendo risultati in controtendenza rispetto alle medie nazionali. Dall&#8217;Osservatorio Provinciale del Mercato del Lavoro comunicano che dal 13 Marzo 2012 al 13 Marzo 2013 il numero dei disoccupati \u00e8 diminuito di ben 180 unit\u00e0. Un dato che si rispecchia anche nell&#8217;andamento del rapporto tra licenziamenti ed assunzioni. A fronte di 1.139 contratti cessati dal primo Gennaio al 13 Marzo 2013 infatti si registrano ben 1.570 nuovi contratti posti in essere. <strong>Stando ai numeri dell&#8217;Osservatorio quindi i lavoratori che hanno perso il posto di lavoro nel 2013 sarebbero stati interamente riassorbiti dal mercato, ed in pi\u00f9 altri 431 dipendenti avrebbero sottoscritto nuovi contratti lavorativi.<\/strong> La percentuale di disoccupati in citt\u00e0, pur essendo ancora estremamente elevata 26,85% , registra un lieve calo rispetto al 2012 che riportava un deficit occupazionale sulla popolazione attiva del 27,24%. Ovviamente si tratta di numeri, dati complessivi che non tengono conto delle situazioni individuali dei cosentini senza lavoro.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p style=\"text-align: justify;\">Al Centro per l&#8217;Impiego di Cosenza infatti gli utenti lamentano carenze enormi nell&#8217;offerta lavorativa. \u201cHo lavorato per sei anni all&#8217;hotel Executive \u2013 afferma un disoccupato all&#8217;uscita di quello che un tempo veniva chiamato il centro di collocamento \u2013 poi dal 2009 quando sono stato licenziato non ho pi\u00f9 lavorato. Ho 35 anni e per fortuna non ho famiglia e vivo con i miei altrimenti la situazione sarebbe intollerabile. Vengo qui almeno una volta a settimana per vedere se ci sono annunci. Telefono a tutti i numeri che sono in bacheca ma in questi anni l&#8217;unica risposta che ho sempre ricevuto \u00e8: &#8216;no grazie, abbiamo gi\u00e0 trovato&#8217;. Allora perch\u00e8 non tolgono l&#8217;annuncio? Ci fanno solo spendere soldi in telefonate inutili. Ci prendono in giro, ma io non smetto di crederci, ci credo ogni volta che appunto il numero di un offerta\u201d. \u201cIo lavoravo con le cooperative sociali \u2013 spiega un altro utente \u2013 da cinuqe anni non sto facendo nulla. Qui ci sono degli annunci, ma le risposte sono sempre negative. Ho fatto centinaia di domande in questi anni e non ho mai avuto nessun riscontro.<strong> Capisco che c&#8217;\u00e8 crisi, noi per\u00f2 veniamo qui per lavorare non per rubare. Io convivo con la mia ragazza che lavora in un call center a 300 euro al mese quando va bene, se no ne prende 250. come si fa a vivere cos\u00ec?\u201d<\/strong>. Le interinali pare invece sortiscano un effetto diverso: \u201csono fortunato \u2013 sostiene un ragazzo appena finito un colloquio \u2013 ho perso il lavoro da un mese e mandando il curriculum via internet mi hanno convocato per avere un primo incontro. Speriamo bene\u201d. I numeri in ogni caso fanno intravedere la luce in fondo al tunnel. Molto in fondo purtroppo.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; COSENZA \u2013 Dati positivi sul fronte occupazionale.<\/p>\n","protected":false},"author":22,"featured_media":19570,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-19569","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19569","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19569"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19569\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19570"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19569"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19569"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19569"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}