{"id":19581,"date":"2013-03-17T10:17:29","date_gmt":"2013-03-17T09:17:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19581"},"modified":"2023-01-17T13:17:27","modified_gmt":"2023-01-17T12:17:27","slug":"7308-si-cerca-la-verita-sul-suicidio-di-alessandro-bozzo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7308-si-cerca-la-verita-sul-suicidio-di-alessandro-bozzo\/","title":{"rendered":"Si cerca la verit\u00e0 sul suicidio di Alessandro Bozzo"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Beh, entriamo nei personaggi.<strong> Era questo l&#8217;urlo di battaglia lavorativo con cui Alessandro Bozzo, iniziava le sue giornate in <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong>redazione, pianificando, tra un sorso di caff\u00e8 e la sigaretta tra le dita, il giornale. Ed \u00e8 con questo spirito, da cronista combattivo e guerriero, che oggi voglio aprire le notizie su quicosenza. Da quel maledetto venerd\u00ec sera, l&#8217;intera classe giornalistica cosentina e calabrese, \u00e8 precipitata in un tunnel, di incredulit\u00e0 e di sconforto. Cerchiamo una spiegazione logica, a quello che di logico in questa tragedia non ha nulla. Alessandro Bozzo il giornalista, professionale e preparato, Alessandro Bozzo, il cronista a cui bastava una mezza soffiata per costruire un articolo e sollevare un dibattito, Alessandro Bozzo, il collega pi\u00f9 &#8220;cazzuto&#8221; con cui ho avuto il piacere di lavorare, ha scelto il modo peggiore per esternare il suo disagio. Quel male di vivere di cui abbiamo spesso scritto e su cui ci siamo spesso confrontati, s&#8217;\u00e8 impossessato anche di lui, facendolo prigioniero e disarmandolo di quella sua corazza da &#8220;duro&#8221; che, credevo caro Alessandro, nessuno sarebbe mai riuscito a toglierti.<\/strong> Di Alessandro, oggi mi restano i suoi articoli, i suoi sorrisi, quella sua capacit\u00e0, quasi unica, di saperti motivare, riuscendo a far emergere il meglio da ognuno di noi, di Alessandro mi rimarranno le battute sui miei baffi, di Alessandro conserver\u00f2, per sempre, ogni singolo ricordo.<strong> Da quella tragica, terribile e disgraziata sera di venerd\u00ec, Alessandro \u00e8 immobile in attesa di essere sepolto. Il suo funerale non \u00e8 ancora stato fissato, ci sono le pratiche giudiziarie da finire e le indagini da terminare. Indagini che, per\u00f2, ancora non sono riuscite a stabilire il perch\u00e8 di quella sua voglia improvvisa, di farla finita, il perch\u00e8 di quella sua scelta, di non voler pi\u00f9 vivere, la causa del black out che ha mandato in tilt il suo interruttore nevralgico. I motivi del suo gesto, Alessandro, prima di impugnare tra le mani la pistola con la quale ha compito il gesto estremo, li ha spiegati in una lettera di tre pagine. Tre fogli ordinati e precisi, lasciati a testimonianza di una decisione sofferta ma meditata, scusandosi con il mondo intero. Tra i tanti messaggi di saluto, postati sui social o sull&#8217;edizione cartacea dei quotidiani locali, c&#8217;\u00e8 anche quello del presidente dell&#8217;ordine nazionale dei giornalisti, Enzo Iacpino. Lui il capo dei giornalisti italiani, vuole vederci chiaro e scrive: Chi ha colpe, chi lo ha ghettizzato, chi lo ha mortificato professionalmente ed economicamente, recuperi un p\u00f2 di buon senso: taccia. Mi ha raccontato &#8211; conclude Iacopino &#8211; scrivendomi in privato, cose miserabili, sulle quali sto facendo ulteriori accertamenti. No, non finir\u00e0 qui&#8221;. Gi\u00e0 Alessandro, non pu\u00f2 e non deve finire cos\u00ec. Ciao amico mio.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Beh, entriamo nei personaggi. Era questo l&#8217;urlo di battaglia lavorativo con cui Alessandro Bozzo, iniziava le sue giornate in<\/p>\n","protected":false},"author":22,"featured_media":19582,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-19581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19581"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19582"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}