{"id":19593,"date":"2013-03-18T10:07:19","date_gmt":"2013-03-18T09:07:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19593"},"modified":"2023-01-17T13:17:27","modified_gmt":"2023-01-17T12:17:27","slug":"7314-krokodil-la-nuova-droga-russa-che-ti-mangia-vivo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7314-krokodil-la-nuova-droga-russa-che-ti-mangia-vivo\/","title":{"rendered":"Krokodil, la nuova droga russa che ti mangia vivo"},"content":{"rendered":"<p><strong>RUSSIA<\/strong> &#8211; Ti mangia la carne, ti distrugge l&#8217;organismo, ti divora. Tutto per due ore di sballo. Si chiama Krokodil ed \u00e8 una droga russa fatta in casa, la causa dell&#8217;aumento di decessi in Russia. E&#8217; proprio da qui che arriva l&#8217;allarme, una<\/p>\n<p>  <!--more-->  <\/p>\n<p>droga sintetica che squarcia la pelle, che mangia il muscolo se non viene iniettato in vena e ti mangia vivo. Molto pi\u00f9 potente dell&#8217;eroina, pi\u00f9 economica che provoca uno sballo pi\u00f9 forte ma meno duraturo. Si ottiene miscelando la codeina all&#8217;olio, alla benzina e al detersivo. Una droga nuova che vince su tutte per la pericolosit\u00e0, per gli effetti devastanti che provoca sul corpo e per il grado altissimo di dipendenza. I tossicodipendenti da Krokodil non hanno un aiuto dallo Stato, una clinica che li porti alla disintossicazione. L&#8217;unica via in cui questi vengono indirizzati \u00e8 il carcere.<\/p>\n<p>Ma quali sono gli effetti della Krokodil? Gi\u00e0 il nome ci indirizza sulla giusta via, un coccodrillo che divora il corpo. Si parte dalle piccole escoriazioni, simili a bruciature di sigaretta circolari che, lentamente, dalla pelle lasciano scoperta la carne, fino ad arrivare alle ossa. Il mix con il quale \u00e8 composta la droga \u00e8 completamente nocivo per il corpo e le conseguenze devastanti arrivano proprio dal contatto della sostanza con il muscolo, riducendono in cancrena. Un costo che varia dai 7 ai 12 euro, contro i 50 dell&#8217;Eroina.<\/p>\n<p>Chi si fa di Krokodil conosce i rischi ma non se ne cura perch\u00e8 la dipendenza \u00e8 troppa, troppa la voglia di sballo, lo stato e il benessere provocato. Basta comprare tutti gli ingredienti in farmacia e conoscere la &#8220;ricetta&#8221;. Un&#8217; iniezione di Krokodil ne richiede un&#8217;altra dopo due ore, e poi ancora dopo due ore, e ancora, fino a diventare un ammasso di carne putrefatta e quasi in decomposizione.<\/p>\n<p>Una realt\u00e0 che spaventa, che disgusta che allarma.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUSSIA &#8211; Ti mangia la carne, ti distrugge l&#8217;organismo, ti divora. Tutto per due ore di sballo. Si chiama Krokodil ed \u00e8 una droga russa fatta in casa, la causa dell&#8217;aumento di decessi in Russia. E&#8217; proprio da qui che arriva l&#8217;allarme, una<\/p>\n","protected":false},"author":22,"featured_media":19594,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,22],"tags":[],"class_list":["post-19593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-dal-mondo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19593"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19594"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}