{"id":19597,"date":"2013-03-18T10:29:01","date_gmt":"2013-03-18T09:29:01","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19597"},"modified":"2023-01-17T13:17:28","modified_gmt":"2023-01-17T12:17:28","slug":"7316-alessandro-come-un-canarino-sei-volato-via","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7316-alessandro-come-un-canarino-sei-volato-via\/","title":{"rendered":"Alessandro: come un canarino, sei volato via"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>COSENZA &#8211;<\/strong> Alessandro raccontato da Eugenio Furia. <strong>Si presenta in redazione un assessore tutto rigido. <\/strong><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><strong>Non eravamo abituati alle visite ufficiali, il giornale era troppo giovane. Infatti no, non era una visita ufficiale ma un politico di quelli che Alessandro amava prendere in giro \u2013 arroganti e (pre)potenti, preferibilmente non troppo distanti dalla sua parte politica, se no che gusto c\u2019era \u2013 che lo aveva appena minacciato al telefono per un pezzo scomodo (no, non sono quelle intimidazioni che vengono riprese dai giornaloni, trattandosi di una di quelle cronachette piccole eppure esemplari di un certo modo di esercitare il potere a Cosenza). Di l\u00ec si tentava di ricucire, mentre lui sghignazzava con noi nello stanzone dei vogatori del galeone. Qualche tempo dopo la cosa si fa un po\u2019 pi\u00f9 seria. Prima della riunione del mattino apre una insolita lettera trovata sulla scrivania: \u00abCazzo, questi mi minacciano di morte!\u00bb.<\/strong> Ma anche quella volta non c\u2019\u00e8 paura, almeno all&#8217;apparenza, solo il sorriso sfottente che adesso ci manca. \u00abUna volta che metti la notizia nelle prime cinque righe, poi non serve pi\u00f9 niente\u00bb. E io qualche suo attacco me lo ricordo perch\u00e9, soprattutto quando inizi, individui subito i pi\u00f9 bravi e li segui (i follower non sono nati con twitter!), ti appassioni mentre sei convinto che stai facendo davvero anche tu il giornalista: \u00abQuando Nicola si accende una paglia vuol dire che ha in mente un\u2019altra idea delle sue\u00bb. E ricordo anche i consigli al pivello (io), suggerimenti travestiti da parere: \u00abInsomma, la notizia \u00e8 che Perux se vince fa Peppino vicesindaco, o no?\u00bb (io mica l&#8217;avevo capito, ed eravamo nello stesso posto!). Sono passati pi\u00f9 di dieci anni&#8230; Ora, da quando lavoravamo di nuovo in giornali diversi, lo \u201cfrequentavo\u201d leggendo i suoi pezzi di cronaca: quando era in vena, rendeva la dinamica di un omicidio una scena da film pulp, o da libro di Welsh, il suo amato Irwin. In uno degli ultimi articoli che ricordo (un agguato a Citt\u00e0 2000) mi \u00e8 sembrato di vederlo che si rotolava a terra con la giacca di velluto il dolcevita la sigaretta i capelli lunghi il dentuzzo affilato e il taccuino, gettandosi dallo sportello come nei poliziotteschi. Un altro giorno l\u2019avevo rivisto in quella foto pubblicata su Vanity Fair, e avevo sorriso riconoscendo l\u2019angolo grigio che abbiamo condiviso per oltre 4 anni: \u00e8 la primavera del 2006 e ci ritroviamo seduti accanto, dopo il precariato (che per lui \u00e8 significato anche esilio), le conferenze stampa insulse e i comunicati in politichese-sindacalese calabro da cercare di decriptare e poi tradurre in italiano (ridendo). In quel capannone cresciamo, forse diventiamo grandi ma solo \u201cufficialmente\u201d, la macchina  la casa, poi negli stessi mesi ci sposiamo e replichiamo, moltiplicandolo, l\u2019amore per una donna divenuta moglie in quello, immenso, per una figlia. <strong>Lui si torturava le ciocche che gli invidiavo, produceva copiose miniature (cura dei dettagli; molte ali e molte lame: leggerezza e lacerazioni) sul bloc notes, in riunione c&#8217;erano risate e anche differenze di vedute e parolacce, fortunatamente. Anche oggi, Alessandro non ha bisogno di peana, i coccodrilli buoni(sti) li odierebbe, poi certo ora siamo tutti suoi amici. \u00abSei un kamikaze!\u00bb. \u00abCome sei cinico\u00bb. \u00abLa leggera non la vuoi fare, ah?\u00bb. \u00abIl pezzo te lo ceselli e le brevine le scacazzi?\u00bb. Gli rimproveravamo di stare \u00abin una campana\u00bb salvo riemergere ogni tanto. La Fiorentina, il tennis, la musica, Donnici e il Canada, le sigarette e il caff\u00e8, i libri. Da quasi tre giorni, ogni tanto piango pensando a tutte queste cose, e ad altre frasi, ad altri episodi che altri colleghi ricordano. Il rimpianto pi\u00f9 forte \u00e8 che non l&#8217;ho mai ringraziato per essere stato il primo a notarmi e volermi nel suo stesso giornale, chiese il numero a mia sorella, si conoscevano dal liceo: per i compagni di classe \u00e8 il ragazzo che disegna benissimo e ama gli U2, chi ha continuato a lavorarci assieme pu\u00f2 confermare che, tra le altre cose, era un finto duro con un cuore tenero. Per dire, non era l\u2019animalista che s\u2019indignava solo quando arrivava il comunicato della polizia provinciale sull\u2019ennesimo bracconiere \u00absgamato\u00bb e le povere vittime esposte in batteria, lui il amava davvero, i canarini. Benedetta mi ha raccontato che una volta ne accud\u00ec uno in redazione, gli dava dei vermetti da mangiare e lo affidava ad altri quando usciva per servizio \u2013 poi un giorno \u00e8 volato via.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Alessandro raccontato da Eugenio Furia. Si presenta in redazione un assessore tutto rigido.<\/p>\n","protected":false},"author":22,"featured_media":19598,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-19597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19597"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19598"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}