{"id":196341,"date":"2023-03-02T11:48:41","date_gmt":"2023-03-02T10:48:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=196341"},"modified":"2023-03-02T12:29:33","modified_gmt":"2023-03-02T11:29:33","slug":"mattarella-a-crotone-la-visita-ai-sopravvissuti-in-ospedale-e-lomaggio-alle-vittime","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/mattarella-a-crotone-la-visita-ai-sopravvissuti-in-ospedale-e-lomaggio-alle-vittime\/","title":{"rendered":"Mattarella a Crotone, la visita ai sopravvissuti in ospedale e il silenzio davanti alle bare"},"content":{"rendered":"<p>CROTONE &#8211; E&#8217; arrivato <a href=\"https:\/\/quicosenza.it\/news\/calabria\/crotone-riaperta-la-camera-ardente-mattarella-ospedale-e-dalle-vittime-del-naufragio\">intorno alle 11 a Crotone<\/a>, dopo essere atterrato all&#8217;aeroporto Sant&#8217;Anna. Scortato in auto fino all&#8217;ospedale San Giovanni di Dio, il presidente della Repubblica Sergio Mattarella, ha voluto prima incontrare i sopravvissuti <strong>ricoverati<\/strong> in ospedale, ovvero <strong>15 persone<\/strong>. Una giornata quella del Capo dello Stato per rendere omaggio alle vittime del naufragio avvenuto domenica mattina nelle acque antistanti Steccato di Cutro. Migranti partiti dalla Turchia, 67 dei quali hanno trovato la morte, tra cui donne e bambini. Altri sono ancora dispersi. Il presidente \u00e8 stato accolto all&#8217;arrivo dagli applausi ma anche da persone che hanno urlato &#8220;<strong>giustizia, giustizia<\/strong>&#8220;. Sempre la folla ha rivolto un appello: &#8220;<strong>presidente, non ci abbandoni<\/strong>&#8220;.<\/p>\n<p>Accolto nel nosocomio dal commissario straordinario dell&#8217;Asp crotonese, Simona Carbone e dal direttore sanitario Lucio Cosentino, \u00e8 stato poi accompagnato nei reparti, anche in quello pediatrico. L&#8217;incontro con i bambini superstiti \u00e8 stato preceduto da alcuni pacchi contenenti <strong>giocattoli fatti consegnare dal presidente Mattarella ai piccoli degenti: <\/strong>peluche, pianole e piccoli robot telecomandati.<\/p>\n<p>Il presidente della Repubblica si \u00e8 poi recato alla camera ardente. All&#8217;ingresso del Palamilone il governatore Roberto Occhiuto, il sindaco di Crotone Vincenzo Voce, il primo cittadino di Cutro, Antonio Ceraso e il vescovo Angelo Panzetta. All&#8217;interno, un <strong>momento di silenzioso raccoglimento davanti alla distesa di bare durato diversi minuti <\/strong>insieme al Prefetto di Crotone, Maria Carolina Ippolito. Mattarella si \u00e8 intrattenuto nel palazzetto con i familiari ed ha poi lasciato il Palamilone, senza rilasciare alcuna dichiarazione. Fuori, \u00e8 stato salutato dagli applausi dei cittadini che ancora una volta gli hanno chiesto <strong>&#8220;giustizia e verit\u00e0&#8221;. <\/strong>Mattarella ha assicurato pieno sostegno ai profughi.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; E&#8217; arrivato intorno alle 11 a Crotone, dopo essere atterrato all&#8217;aeroporto Sant&#8217;Anna. Scortato in auto fino all&#8217;ospedale San Giovanni di Dio, il presidente della Repubblica Sergio Mattarella, ha voluto prima incontrare i sopravvissuti ricoverati in ospedale, ovvero 15 persone. Una giornata quella del Capo dello Stato per rendere omaggio alle vittime del naufragio [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":196344,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-196341","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/196341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=196341"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/196341\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/196344"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=196341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=196341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=196341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}