{"id":196948,"date":"2023-03-10T11:03:15","date_gmt":"2023-03-10T10:03:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=196948"},"modified":"2023-03-10T11:03:15","modified_gmt":"2023-03-10T10:03:15","slug":"operazione-infinito-carabinieri-sgomberano-ambulatorio-della-ndrangheta-in-brianza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/operazione-infinito-carabinieri-sgomberano-ambulatorio-della-ndrangheta-in-brianza\/","title":{"rendered":"Operazione Infinito, carabinieri sgomberano ambulatorio della &#8216;ndrangheta in Brianza"},"content":{"rendered":"<p>MONZA &#8211; Un poliambulatorio \u00e8 stato<strong> sgomberato dai carabinieri e dalla Polizia locale a Seregno (Monza), perch\u00e9 confiscato alla mafia a seguito della maxi indagine &#8216;Infinito&#8217;,<\/strong> l&#8217;operazione dei carabinieri del Nucleo Investigativo di Monza contro la &#8216;ndrangheta lombarda.<\/p>\n<p>Insieme al personale dell&#8217;Agenzia nazionale per l&#8217;amministrazione e la destinazione dei beni sequestrati e confiscati alla criminalit\u00e0 organizzata, i carabinieri hanno eseguito <strong>l&#8217;ordinanza di sgombero coatto della struttura, sotto il coordinamento della Prefettura di Monza e Brianza<\/strong>, provvedendo al cambio della serratura e acquisendo il materiale e gli arredi del poliambulatorio, che era stato avviato dai parenti di un esponente della criminalit\u00e0 organizzata di Desio (Monza).<strong> Il bene \u00e8 gi\u00e0 destinato al Comune di Seregno nell&#8217;ambito del progetto &#8216;Agenzia per l&#8217;abitare&#8217;.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONZA &#8211; Un poliambulatorio \u00e8 stato sgomberato dai carabinieri e dalla Polizia locale a Seregno (Monza), perch\u00e9 confiscato alla mafia a seguito della maxi indagine &#8216;Infinito&#8217;, l&#8217;operazione dei carabinieri del Nucleo Investigativo di Monza contro la &#8216;ndrangheta lombarda. Insieme al personale dell&#8217;Agenzia nazionale per l&#8217;amministrazione e la destinazione dei beni sequestrati e confiscati alla criminalit\u00e0 [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":194479,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-196948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/196948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=196948"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/196948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/194479"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=196948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=196948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=196948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}