{"id":19722,"date":"2013-03-19T14:03:36","date_gmt":"2013-03-19T13:03:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19722"},"modified":"2023-01-17T13:17:34","modified_gmt":"2023-01-17T12:17:34","slug":"7383-la-calabria-ricorda-lilius-inventore-del-calendario","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7383-la-calabria-ricorda-lilius-inventore-del-calendario\/","title":{"rendered":"La Calabria ricorda Lilius, inventore del calendario"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211; L&#8217;assessore Mario Caligiuri, nell&#8217;annunciare gli appuntamenti per ricordare, ogni 21 marzo, il giorno dell&#8217;equinozio di primavera &#8220;Aloysius<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Lilius&#8221;, l&#8217;inventore del calendario perfetto che dal 1582 scandisce il tempo del mondo, ha affermato che &#8220;la Calabria e&#8217; terra di grande cultura, da riscoprire e valorizzare. Appunto per questo &#8211; ha detto &#8211; il Consiglio regionale ha votato una legge per dedicare questa giornata alla memoria dello scienziato di Ciro&#8217;, dove si svolgeranno una seria di iniziative.<\/p>\n<p style=\"text-align: justify;\">Festeggiare la prima giornata su Aloysius Lilius a Ciro&#8217; &#8211; ha evidenziato ancora Caligiuri &#8211; e&#8217; un atto dovuto. A Ciro&#8217; esiste anche un museo a lui dedicato e inaugurato da Antonino Zichichi. Negli anni a venire &#8211; ha infine auspicato l&#8217;assessore Caligiuri &#8211; dovremo organizzare eventi sempre piu&#8217; significativi per fare conoscere al mondo questo grande uomo di scienza calabrese&#8221;.<\/p>\n<p style=\"text-align: justify;\">Alla prima giornata regionale in ricordo dell&#8217;equinozio di primavera &#8220;Aloysius Lilius&#8221;, che si svolgera&#8217; al centro diurno &#8220;Alessandro Vitetti&#8221; di Ciro&#8217;, a partire dalle ore 10,30, interverranno &#8211; informa una nota dell&#8217;ufficio stampa della Giunta &#8211; il presidente della Regione Giuseppe Scopelliti, l&#8217;assessore Mario Caligiuri, il sindaco di Ciro&#8217; Mario Caruso, il presidente della Provincia di Crotone Stanislao Zurlo, l&#8217;arcivescovo di Crotone Domenico Graziani. Relazioneranno, inoltre, Pietro De Leo, ordinario emerito di storia medievale e presidente dell&#8217;Istituto internazionale di epistemologia &#8220;La magna Grecia&#8221;, Massimo Mazzoni dell&#8217;Universita&#8217; di Firenze, Romano Gatto dell&#8217;Universita&#8217; della Basilicata, Eugenio De Rose, cultore di storia medievale, Ignazio Filice, cultore di studi &#8220;Liliani&#8221; e Francesco Vizza del Consiglio nazionale delle ricerche di Firenze.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; L&#8217;assessore Mario Caligiuri, nell&#8217;annunciare gli appuntamenti per ricordare, ogni 21 marzo, il giorno dell&#8217;equinozio di primavera &#8220;Aloysius<\/p>\n","protected":false},"author":22,"featured_media":19723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-19722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19722"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19722\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19723"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}