{"id":197338,"date":"2023-03-18T13:30:34","date_gmt":"2023-03-18T12:30:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=197338"},"modified":"2023-03-18T14:17:38","modified_gmt":"2023-03-18T13:17:38","slug":"case-green-via-libera-alla-direttiva-che-ridurra-il-peso-delle-bollette-ecco-cosa-prevede","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/case-green-via-libera-alla-direttiva-che-ridurra-il-peso-delle-bollette-ecco-cosa-prevede\/","title":{"rendered":"Case green, via libera alla direttiva che ridurr\u00e0 il peso delle bollette: ecco cosa prevede"},"content":{"rendered":"<div>\n<div dir=\"auto\">COSENZA &#8211; &#8220;Il Parlamento europeo ha approvato la proposta di direttiva sull&#8217;efficientamento energetico degli edifici. Il Movimento 5 stelle da tempo sostiene che fra gli obiettivi primari dell&#8217;Unione europea ci debba essere il contrasto alla povert\u00e0 energetica e quindi la riduzione del peso delle bollette sulle famiglie&#8221;. A dirlo la <strong>deputata europarlamentare del M5S Laura Ferrara<\/strong>.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div>\n<div dir=\"auto\">Riqualificare un edificio \u00e8 un investimento, affossando il Superbonus, la destra in Italia ha lasciato ai soli ricchi la possibilit\u00e0 di rendere le proprie case sicure, efficienti e sostenibili. Affrontare la sfida del<strong> Green new deal e dell&#8217;abbattimento dei costi energetici<\/strong> \u00e8 possibile solo se si offre a tutti i cittadini la possibilit\u00e0 di ristrutturare gli immobili.<\/div>\n<div dir=\"auto\"><\/div>\n<\/div>\n<div>\n<div dir=\"auto\">Nel testo votato marted\u00ec scorso si chiede, fra le altre cose, la creazione di un fondo dedicato, l&#8217;Energy Performance Renovation Fund, come chiedeva il MoVimento 5 Stelle, per <strong>rendere la transizione sostenibile davvero equa per tutti \u00e8 infatti essenziale<\/strong> che i governi abbiano maggiori risorse oltre a quelle gi\u00e0 esistenti&#8221;, conclude l&#8217;europarlamentare Laura Ferrara in una nota.<\/div>\n<\/div>\n<h3 dir=\"auto\">Cosa prevede la direttiva UE<\/h3>\n<div>\n<div dir=\"auto\">La bozza della direttiva Ue approvata oggi dal Parlamento Europeo prevede che gli edifici residenziali e le unit\u00e0 immobiliari in territorio UE <b>raggiungano almeno la classe energetica E entro il 1\u00b0 gennaio 2030<\/b>\u00a0e almeno la classe di prestazione energetica D entro il 1\u00b0 gennaio 2033.<\/p>\n<p spellcheck=\"true\">La direttiva europea fissa anche l&#8217;<b>obbligatoriet\u00e0 dei pannelli solari per tutti i nuovi edifici pubblici<\/b>\u00a0e anche per quelli non residenziali di nuova costruzione, con scadenze diverse. Tutti gli edifici pubblici e gli edifici non residenziali esistenti dovranno essere dotati di pannelli solari entro il 31 dicembre 2026, mentre l&#8217;obbligo verr\u00e0 esteso a tutti gli edifici sottoposti a ristrutturazioni importanti entro il 31 dicembre 2032.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Il Parlamento europeo ha approvato la proposta di direttiva sull&#8217;efficientamento energetico degli edifici. Il Movimento 5 stelle da tempo sostiene che fra gli obiettivi primari dell&#8217;Unione europea ci debba essere il contrasto alla povert\u00e0 energetica e quindi la riduzione del peso delle bollette sulle famiglie&#8221;. A dirlo la deputata europarlamentare del M5S Laura [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":197339,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-197338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/197338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=197338"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/197338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/197339"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=197338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=197338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=197338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}