{"id":197907,"date":"2023-03-26T19:00:05","date_gmt":"2023-03-26T17:00:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=197907"},"modified":"2023-03-22T16:49:02","modified_gmt":"2023-03-22T15:49:02","slug":"nuovo-record-negativo-per-le-nascite-ma-il-sud-registra-07","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/nuovo-record-negativo-per-le-nascite-ma-il-sud-registra-07\/","title":{"rendered":"Nuovo record negativo per le nascite. Ma il Sud registra +0,7%"},"content":{"rendered":"<p>ROMA &#8211; <strong>Ancora un record negativo per le nascite in Italia<\/strong>. Nel 2022 sono state 392.598: 7.651 in meno rispetto al 2021, pari a -1,9%. Ma la novit\u00e0 \u00e8 che nel Sud, isole escluse, c&#8217;\u00e8 stato un incremento delle nascite di +0,7% rispetto al 2021. A livello territoriale il tasso di natalit\u00e0 conferma ancora una volta il primato della provincia autonoma di Bolzano con il 9,2 per mille, mentre la Sardegna presenta il valore pi\u00f9 basso: 4,9 per mille.<\/p>\n<p>A dirlo \u00e8<strong> l&#8217;Istat nel report &#8220;Dinamica demografica &#8211; Anno 2022&#8221;<\/strong> spiegando che a livello europeo la situazione registrata nel nostro Paese non \u00e8 un&#8217;eccezione, visto che la Spagna ha una situazione simile all&#8217;Italia e la Francia, pur facendo rilevare livelli di fecondit\u00e0 storicamente pi\u00f9 elevati, nel 2022 registra un calo soprattutto a partire dal mese di luglio.<\/p>\n<p>E <strong>in Italia continua a diminuire la popolazione: al 31 dicembre 2022 i residenti sono scesi sotto i 59 milioni<\/strong>, precisamente 58.850.717 ovvero 179.416mila in meno, pari -0,3% rispetto al 2021, nonostante il positivo contributo del saldo migratorio con l&#8217;estero, dovuto soprattutto alla crisi in Ucraina. Il deficit di popolazione rallenta al Nord e peggiora nel Mezzogiorno. Nel Nord il decremento \u00e8 di -0,1%, di entit\u00e0 decisamente inferiore rispetto a quella dell&#8217;anno precedente (-0,4% nel 2021). Anche al Centro il calo di popolazione \u00e8 pi\u00f9 contenuto (-0,3% contro il -0,5% del 2021).<\/p>\n<h3>Nascite: al Sud +0,7%<\/h3>\n<p>Il Mezzogiorno, invece, subisce effetti pi\u00f9 pronunciati passando dal -0,2% del 2021 al -0,6% nel 2022. Un saldo naturale della popolazione che l&#8217;Istat definisce &#8220;fortemente negativo&#8221; anche perch\u00e8 risente ancora degli strascichi della pandemia. E a dimostrarlo il fatto che al termine dello stato di emergenza sanitaria, <strong>a fine marzo 2022 ,la perdita di popolazione registrata nel primo trimestre risulta ben il 46,4%<\/strong> del calo conseguito nell&#8217;intero anno.<\/p>\n<p>A questo si aggiunge il successivo calo di nascite e l&#8217;eccesso di mortalit\u00e0 dei mesi estivi, legato alle persistenti ondate di calore che hanno colpito soprattutto gli anziani. Nel 2022 sono stati 713.499 i decessi, circa 12mila in pi\u00f9 rispetto all&#8217;anno precedente ma 27mila in meno rispetto al 2020, anno di massima mortalit\u00e0 dovuta alla pandemia da Covid-19. A luglio e agosto si \u00e8 registrato un numero di decessi superiore del 16% pari a 125 mila persone, come avvenne nel 2015 quando morirono 110 mila persone per ragioni legate sempre a fattori climatici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Ancora un record negativo per le nascite in Italia. Nel 2022 sono state 392.598: 7.651 in meno rispetto al 2021, pari a -1,9%. Ma la novit\u00e0 \u00e8 che nel Sud, isole escluse, c&#8217;\u00e8 stato un incremento delle nascite di +0,7% rispetto al 2021. A livello territoriale il tasso di natalit\u00e0 conferma ancora una [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":133378,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-197907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/197907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=197907"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/197907\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/133378"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=197907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=197907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=197907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}