{"id":197963,"date":"2023-03-26T13:00:40","date_gmt":"2023-03-26T11:00:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=197963"},"modified":"2023-03-26T13:33:54","modified_gmt":"2023-03-26T11:33:54","slug":"metamateriali-lunical-vince-il-marie-curie-con-il-ricercatore-cosentino-laureti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/metamateriali-lunical-vince-il-marie-curie-con-il-ricercatore-cosentino-laureti\/","title":{"rendered":"Metamateriali, l&#8217;Unical vince il &#8216;Marie Curie&#8217; con il ricercatore cosentino Laureti"},"content":{"rendered":"<p>RENDE (CS) &#8211; Un progetto scientifico guidato dall\u2019Universit\u00e0 della Calabria sull\u2019utilizzo dei metamateriali in applicazioni biomediche ed energetiche \u00e8 risultato vincitore di un bando <strong>Marie Sk\u0142odowska-Curie Actions (Msca)<\/strong>, il programma faro dell&#8217;Unione europea per il finanziamento di dottorati e formazione post-dottorato inserito nell\u2019iniziativa Horizon Europe.<\/p>\n<h3><strong>L\u2019UNICAL E IL PROGETTO METACMED<\/strong><\/h3>\n<p>Il coordinatore del progetto\u00a0<strong>Metacmed\u00a0<\/strong>(Acoustic and mechanical metamaterials for biomedical and energy harvesting applications) \u00e8\u00a0<strong>Stefano Laureti<\/strong>\u00a0del dipartimento di Ingegneria informatica, modellistica, elettronica e sistemistica (Dimes) dell\u2019Unical.<\/p>\n<p>L\u2019obiettivo principale di Metacmed \u00e8 creare una nuova generazione di scienziati (early stage researcher) con una visione inter e multidisciplinare nell\u2019ambito dei metamateriali acustici a meccanici, applicati al miglioramento della salute dell\u2019essere umano a tutto tondo. I\u00a0<strong>metamateriali<\/strong>\u00a0sono materiali contenenti strutture ingegnerizzate che conferiscono propriet\u00e0 meccaniche e acustiche extra-ordinarie, non comunemente disponibili in natura.<\/p>\n<h3><strong>LE POSSIBILI APPLICAZIONI DEI METAMATERIALI<\/strong><\/h3>\n<p>Da Metacmed potrebbero nascere, ad esempio,\u00a0suole innovative per scarpe, capaci di alleviare i sintomi del\u00a0<strong>piede diabetico<\/strong>\u00a0(malattia degenerativa associata al diabete) e, allo stesso tempo, di raccogliere energia meccanica durante la camminata. Oppure dispositivi biomedicali che possano migliorare le caratteristiche meccaniche dei dispositivi usati negli\u00a0<strong>interventi chirurgici su pazienti affetti da ernia del disco<\/strong>, rendendole pi\u00f9 simili a quelle naturali del tessuto discale danneggiato.<\/p>\n<p>Altre applicazioni della ricerca di Metacmed riguardano la realizzazione di cristalli fononici per aumentare la qualit\u00e0 dell\u2019<strong>harmonic imaging ultrasonora\u00a0<\/strong>\u2013 il cui contenuto informativo \u00e8 usato come monitoraggio per trattamenti anti-tumorali all\u2019interno del cranio \u2013 o di pannelli per extra-isolamento dal rumore di calpestio indoor, con sistemi integrati di energy harvesting per il recupero di energia meccanica durante la camminata.<\/p>\n<h3><strong>AZIENDE, UNIVERSIT\u00c0 E CENTRI DI RICERCA<\/strong><\/h3>\n<p>Le azioni Marie Sk\u0142odowska-Curie si basano sui principi di\u00a0mobilit\u00e0 fisica, scambio di conoscenze e cooperazione scientifica.<strong>\u00a0<\/strong>Per questo verranno finanziate 10 posizioni di dottorato presso i centri del consorzio, di cui\u00a0<strong>due presso il Dimes dell\u2019Universit\u00e0 della Calabria<\/strong>.<\/p>\n<p>Gli altri membri di Metacmed sono il Centre national de la recherche scientifique \u2013 Cnrs (Francia), l\u2019Universit\u00e0 degli studi di Messina (Italia), l\u2019Instytut Maszyn Przeplywowych im. Roberta Szewalskiego Polskiej Akademii Nauk \u2013 Imp Pan (Polonia), The University of Warwick (Regno Unito), Eidgen\u00f6ssische Materialpr\u00fcfungs &#8211; und Forschungsanstalt (Svizzera), il Politecnico di Bari (Italia),\u00a0Amazemet Sp. z o.o. (Polonia), InnoSpina Llc (Svizzera), l\u2019\u00c9cole polytechnique f\u00e9d\u00e9rale de Lausanne (Svizzera), Skills4Science (Spagna) e Universit\u00e9 de Lille (Francia).<\/p>\n<p>La squadra Unical all\u2019interno di Metacmed \u00e8 composta anche da Marco Ricci, Andrea Tagarelli, Domenico Luca Carn\u00ec e Marco Mercuri,<strong>\u00a0<\/strong>tutti del Dimes. Il progetto \u00e8 stato finanziato nell\u2019ambito dell\u2019iniziativa Horizon-Msca-2022-Dn-01 con un budget complessivo di<strong>2.786.947 euro<\/strong>, di cui\u00a0<strong>518.875<\/strong>\u00a0<strong>euro\u00a0<\/strong>all\u2019ateneo di Arcavacata per il ruolo di\u00a0capofila.<\/p>\n<p>(fonte dipartimento di Ingegneria informatica, modellistica, elettronica e sistemistica)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; Un progetto scientifico guidato dall\u2019Universit\u00e0 della Calabria sull\u2019utilizzo dei metamateriali in applicazioni biomediche ed energetiche \u00e8 risultato vincitore di un bando Marie Sk\u0142odowska-Curie Actions (Msca), il programma faro dell&#8217;Unione europea per il finanziamento di dottorati e formazione post-dottorato inserito nell\u2019iniziativa Horizon Europe. L\u2019UNICAL E IL PROGETTO METACMED Il coordinatore del progetto\u00a0Metacmed\u00a0(Acoustic and [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":197965,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-197963","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/197963","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=197963"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/197963\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/197965"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=197963"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=197963"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=197963"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}