{"id":198427,"date":"2023-03-27T12:58:41","date_gmt":"2023-03-27T10:58:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=198427"},"modified":"2023-03-27T12:58:41","modified_gmt":"2023-03-27T10:58:41","slug":"terme-sibarite-fincalabra-entra-nel-capitale-sociale-acquisito-il-70","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/terme-sibarite-fincalabra-entra-nel-capitale-sociale-acquisito-il-70\/","title":{"rendered":"Terme Sibarite: Fincalabra entra nel capitale sociale, acquisito il 70%"},"content":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; La presidenza delle Terme Sibarite ha comunicato che &#8220;Fincalabra spa, organismo &#8216;in house providing&#8217; della Regione che opera a sostegno del sistema produttivo regionale, \u00e8 <strong>entrata nel capitale sociale di Terme Sibarite<\/strong>, societ\u00e0 per azioni proprietaria dello stabilimento termale di Cassano Ionio, sin qui interamente partecipata dalla stessa Regione Calabria&#8221;.<\/p>\n<p>&#8220;<strong>L&#8217;importo complessivo<\/strong> sottoscritto da Fincalabra spa, gi\u00e0 <strong>interamente versato<\/strong> &#8211; \u00e8 scritto nella nota &#8211; porta la societ\u00e0 finanziaria per lo sviluppo economico della Calabria a detenere in Terme Sibarite spa una quota di partecipazione pari a <strong>circa il 70%<\/strong>&#8220;.<\/p>\n<p>&#8220;L&#8217;operazione, finanziata attraverso accesso al fondo Exit Strategy Fuif, rientra nell&#8217;ambito della legge regionale 16 del 6 giugno 2022, attraverso la quale si demandava proprio a Terme Sibarite spa e a Fincalabra spa il compito di &#8216;intraprendere tutte le iniziative occorrenti per la creazione della rete regionale delle terme, intesa come sistema integrato dei servizi e delle prestazioni di settore, volta a <strong>favorire la qualificazione del patrimonio idrotermale, ricettivo e turistico<\/strong>&#8216;, dando avvio a un percorso che gi\u00e0 nel luglio del 2022 aveva portato proprio Terme Sibarite spa alla stipula di un contratto di fitto di ramo di azienda &#8211; con espressa previsione di un diritto di opzione per l&#8217;acquisizione dello stesso &#8211; finalizzato alla gestione dello stabilimento ThermaeNovae di Acquappesa e delle collegate strutture ricettive&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; La presidenza delle Terme Sibarite ha comunicato che &#8220;Fincalabra spa, organismo &#8216;in house providing&#8217; della Regione che opera a sostegno del sistema produttivo regionale, \u00e8 entrata nel capitale sociale di Terme Sibarite, societ\u00e0 per azioni proprietaria dello stabilimento termale di Cassano Ionio, sin qui interamente partecipata dalla stessa Regione Calabria&#8221;. [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":190842,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-198427","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/198427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=198427"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/198427\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/190842"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=198427"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=198427"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=198427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}