{"id":198607,"date":"2023-03-29T10:13:17","date_gmt":"2023-03-29T08:13:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=198607"},"modified":"2023-03-29T10:13:17","modified_gmt":"2023-03-29T08:13:17","slug":"cosenza-annunziata-al-via-il-corso-di-rianimazione-neonatale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-annunziata-al-via-il-corso-di-rianimazione-neonatale\/","title":{"rendered":"Cosenza, Annunziata: al via il corso di Rianimazione Neonatale"},"content":{"rendered":"<p>COSENZA &#8211; Si terr\u00e0 il 30 e 31 marzo all\u2019ospedale Annunziata di Cosenza<strong>, il corso di Rianimazione neonatale, promosso dalla Societ\u00e0 Italiana di Neonatologia<\/strong> e destinato agli operatori sanitari dei Punti Nascita della Regione Calabria:<strong> Medici Neonatologi, Pediatri, Anestesisti-Rianimatori, Infermieri e Ostetriche<\/strong>\u00a0al quale<br \/>\nall\u2019evento formativo, hanno aderito molti operatori <strong>dei Punti nascita della provincia di Cosenza, di Catanzaro e di Vibo Valentia<\/strong>, prevede lezioni teoriche e prove pratiche, si svolger\u00e0 nella Biblioteca del P.O. Annunziata per quanto riguarda la teoria e in Sala Parto per quanto riguarda le procedure di rianimazione.<\/p>\n<p>\u201cObiettivo del Corso &#8211; ha dichiarato <strong>il dottor Scarpelli, Direttore del Dipartimento Materno Infantile<\/strong> &#8211; \u00e8 fornire gli strumenti necessari a garantire il miglioramento dell\u2019assistenza del neonato in sala parto attraverso<strong> l\u2019aggiornamento in materia di conoscenze teoriche ed esercitazioni pratiche<\/strong> di rianimazione neonatale\u201d.<\/p>\n<p>\u201cLa formazione e l\u2019aggiornamento degli operatori sanitari &#8211; ha aggiunto Scarpelli &#8211; rappresenta un elemento fondamentale di crescita dell\u2019Azienda. In considerazione della complessit\u00e0 del lavoro svolto in sala parto,<strong> riteniamo necessario promuovere una conoscenza pi\u00f9 completa ed innovativa delle manovre rianimatorie<\/strong> e delle procedure di stabilizzazione, indispensabili alla gestione ottimale del neonato critico, essendo i primi momenti di vita cruciali e determinanti per la futura vita del bambino\u201d.<br \/>\nVivo apprezzamento \u00e8 stato espresso dal Commissario Straordinario per l\u2019iniziativa che la Societ\u00e0 Italiana di Neonatologia ha voluto organizzare a Cosenza.<strong> \u201cSiamo ben lieti \u2013 ha affermato De Salazar<\/strong> &#8211; di accogliere questa sessione formativa utile ai cambiamenti in corso\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Si terr\u00e0 il 30 e 31 marzo all\u2019ospedale Annunziata di Cosenza, il corso di Rianimazione neonatale, promosso dalla Societ\u00e0 Italiana di Neonatologia e destinato agli operatori sanitari dei Punti Nascita della Regione Calabria: Medici Neonatologi, Pediatri, Anestesisti-Rianimatori, Infermieri e Ostetriche\u00a0al quale all\u2019evento formativo, hanno aderito molti operatori dei Punti nascita della provincia di [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":173587,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-198607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/198607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=198607"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/198607\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/173587"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=198607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=198607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=198607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}