{"id":198906,"date":"2023-04-01T11:30:32","date_gmt":"2023-04-01T09:30:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=198906"},"modified":"2023-04-01T13:55:43","modified_gmt":"2023-04-01T11:55:43","slug":"a-bisignano-lassemblea-annuale-dei-periti-agrari-del-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/a-bisignano-lassemblea-annuale-dei-periti-agrari-del-cosentino\/","title":{"rendered":"A Bisignano l&#8217;Assemblea annuale dei Periti Agrari del Cosentino"},"content":{"rendered":"<p>BISIGNANO (CS) &#8211; Il \u201cVivaio San Paolo\u201d in contrada Campovile a Bisignano, ha ospitato lo scorso 25 marzo l\u2019Assemblea annuale dei Periti Agrari e Periti Agrari Laureati della provincia di Cosenza per <strong>l\u2019approvazione del bilancio consuntivo 2022<\/strong> e di quello <strong>preventivo<\/strong> per l\u2019annualit\u00e0 2023. L\u2019assemblea si \u00e8 aperta con la relazione del Presidente del Collegio, Cataldo Maio, che ha riassunto le attivit\u00e0 del 2022, purtroppo ancora condizionate dalla pandemia, come del resto per tutta l\u2019ultima consiliatura.<\/p>\n<p>&#8220;L\u2019assemblea, molto partecipata &#8211; ha continuato il presidente &#8211; ci riporta la rappresentazione plastica di un <strong>Collegio sempre pi\u00f9 unito e coeso<\/strong>, proiettato sul consolidamento della propria governance e sulla strutturazione di un\u2019organizzazione capace di rispondere concretamente alle richieste dei suoi stessi iscritti. Vieppi\u00f9, la possibilit\u00e0 di concretizzare altri due obiettivi specifici del nostro Collegio: promuovere e consolidare uno stretto rapporto con il territorio e le istituzioni nonch\u00e9 sostenere la figura professionale del Perito Agrario al fine di ottenere un ancor maggiore coinvolgimento degli iscritti, propedeutico all\u2019implementazione di una rete professionale capace di rispondere ai quesiti legati al territorio di riferimento nonch\u00e9 alla professione stessa&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-198908 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2.jpg\" alt=\"\" width=\"501\" height=\"310\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-2-356x220.jpg 356w\" sizes=\"auto, (max-width: 501px) 100vw, 501px\" \/><\/p>\n<p>Nella seconda parte dell\u2019assemblea gli iscritti hanno potuto <strong>prendere visione del bilancio<\/strong> e l\u2019approvazione all\u2019unanimit\u00e0 dello stesso ha comprovato, ha detto ancora Maio, come i processi di gestione siano fortemente condivisi da tutti. Nell\u2019ultima parte, gli iscritti hanno avuto la possibilit\u00e0 di intervenire e di porre all\u2019attenzione del Collegio svariate proposte come: l\u2019intensificazione della formazione professionale e degli incontri tra pari per condividere eventuali problematiche ed arrivare a soluzioni concertate. Tutti d\u2019accordo altres\u00ec, sulla necessit\u00e0 di agire in modo univoco e compatto, al fine di difendere le nostre aziende, i nostri allevatori e agricoltori locali dalle insidie di riforme capziose, costi crescenti e globalizzazione dilagante.<\/p>\n<p>L\u2019intervento del segretario <strong>Edmondo Minisci<\/strong> ha invece riportato l\u2019attenzione in merito allo sviluppo delle aziende, alla commercializzazione dei prodotti locali ed al loro riconoscimento, mentre il prof. Angelo Rosa ha messo in luce la DOP \u201cFichi di Cosenza\u201d e la collaborazione con l\u2019Universit\u00e0 di Reggio Calabria, l\u2019ARSAC ed il Vivaio San Paolo; le tecniche di riproduzione, coltivazione e commercializzazione. Infine l\u2019intervento del Perito Agrario, Giuseppe Ammirata che ha descritto e presentato il vivaio, elogiando il servizio RAI di \u201cLinea Verde\u201d sul Fico Dottato di Cosenza. L\u2019assemblea si \u00e8 conclusa con una visita guidata all\u2019interno del vivaio che ha preceduto i ringraziamenti dell\u2019intero Consiglio direttivo e dei Revisori dei Conti, con il proposito di rincontrarsi in altre giornate tematiche.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-198909 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3.jpg\" alt=\"\" width=\"507\" height=\"314\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/04\/Periti-agrari-bisignano-3-356x220.jpg 356w\" sizes=\"auto, (max-width: 507px) 100vw, 507px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BISIGNANO (CS) &#8211; Il \u201cVivaio San Paolo\u201d in contrada Campovile a Bisignano, ha ospitato lo scorso 25 marzo l\u2019Assemblea annuale dei Periti Agrari e Periti Agrari Laureati della provincia di Cosenza per l\u2019approvazione del bilancio consuntivo 2022 e di quello preventivo per l\u2019annualit\u00e0 2023. L\u2019assemblea si \u00e8 aperta con la relazione del Presidente del Collegio, [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":198907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-198906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/198906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=198906"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/198906\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/198907"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=198906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=198906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=198906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}