{"id":19940,"date":"2013-03-22T09:12:58","date_gmt":"2013-03-22T08:12:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=19940"},"modified":"2023-01-17T13:17:46","modified_gmt":"2023-01-17T12:17:46","slug":"7492-lsu-lpusiamo-stanchi-di-precarieta-e-norme-transitorievogliamo-normalita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7492-lsu-lpusiamo-stanchi-di-precarieta-e-norme-transitorievogliamo-normalita\/","title":{"rendered":"Lsu-Lpu:&#8221;Siamo stanchi della precariet\u00e0.Vogliamo normalit\u00e0&#8221;."},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><strong>REGGIO CALABRIA<\/strong> &#8211; &#8220;Salvaguardati i lavoratori essenziale per il funzionamento degli enti&#8221;. Approvata la legge del consiglio regionale che consente di colmare il vuoto legislativo<\/p>\n<p>  <!--more-->  <\/p>\n<p>creatosi con la sentenza n. 18 della Corte Costituzionale, la possibilit\u00e0 di tirare un vero e proprio sospiro di sollievo da parte di quei padri di famiglia che vivono nel dramma della precariet\u00e0, diventati con il tempo lavoratori essenziali ed indispensabili per il funzionamento degli enti. I lavori socialmente utili o LSU sono nati come una politica attiva del lavoro in Italia, basati sulla partecipazione ad iniziative di pubblica utilit\u00e0 limitate nel tempo per soggetti svantaggiati nel mercato del lavoro. La categoria dei lavoratori di pubblica utilit\u00e0 (LPU) rientra in quella dei lavoratori socialmente utili (LSU).<\/p>\n<p>Una rappresentanza di lavoratori Lsu-Lpu \u00e8 stata accolta dal presidente del Consiglio regionale Francesco Talarico, il presidente della Giunta Giuseppe Scopelliti e i capigruppo consiliari i quali, nel corso di una Conferenza, nella quale i rappresentanti di Cgil, Cisl e Uil &nbsp;hanno esposto le ragioni e le preoccupazioni a seguito della sentenza n.18 della Corte Costituzionale che dichiarava l\u2019illegittimit\u00e0 dell\u2019art.55 della legge regionale n.47 2011 relativa all\u2019attuazione del Piano di stabilizzazione del personale, \u00e8 scaturita la necessit\u00e0 di un percorso condiviso all\u2019insegna della responsabilit\u00e0 e della certezza dell\u2019operato che il Consiglio regionale dovr\u00e0 assumere riguardo una questione cos\u00ec delicata e complessa che interessa quasi 5000 lavoratori calabresi e che necessita di relativa copertura finanziaria. Il lavoro dei Lsu e Ipu, infatti, garantisce il funzionamento di servizi essenziali in enti che altrimenti non disporrebbero della possibilit\u00e0 organizzative e della risorse umane necessarie per soddisfare le esigenze dei cittadini. La proposta di legge assicura il finanziamento dei progetti presentati dagli enti proponenti e demarca alla giunta regionale la predisposizione di un&#8217;organiza disciplina normativva in materia di lavori socialmente utili e di pubblica utilit\u00e0, tenuto conto dei dettati di legge. L&#8217;utilizzo dei fondi disponibili e quantificati in 21 milioni di euro rende certa l&#8217;erogazione del sussidio, delle ore integrative e dell&#8217;assegno al nucleo familiare ai lavoratori di pubblica utilit\u00e0, nonch\u00e8 l&#8217;erogazione delle ore integrative ai lavoratori socialmente utili gi\u00e0 sussidiati, per tramite dell&#8217;Inps, dalla Regione Calabria e dal Ministero del Lavoro e Politiche sociali ex art. 78, commi 2 e 3, della legge 288\/2000. Il sindaco di Rovito, Felice D&#8217;Alessandro, esprime e afferma la totale e piena solidariet\u00e0 ai lavoratori LSU\/LPU:&#8221;\u201cVorrei, in questa sede, ribadire l&#8217;importanza determinanate delle diverse figure utilizzate all&#8217;interno degli Enti. La loro operosit\u00e0, il loro impegno e la loro costanza, nonch\u00e9 il fondamentale contributo al buon andamento nella gestione e fruizione dei servizi. Rappresentano motivi pi\u00f9 che validi affinch\u00e8 sia, in tempi brevi, trovata rapida soluzione in grado di rispondere alle legittime esigenze dei lavoratori. Come amministratore non posso dimenticare che dare riconoscimento, dignit\u00e0, certezze a chi ogni giorno nel silenzio del proprio operare contribuisce alla crescita e al funzionamento della macchina amministrativa, sia uno dei capisaldi su cui \u00e8 necessario fondare, ora pi\u00f9 che mai, una democrazia solida, libera e plurale ma soprattutto giusta\u201d.<\/p>\n<p>In una nota il Vicepresidente del Consiglio regionale, Alessandro Nicolo&#8217;:&#8221;L&#8217;approvazione del testo di legge per il mantenimento delle convenzioni degli Lpu-Lsu nelle amministrazioni pubbliche negli enti locali calabresi, e&#8217; la riaffermazione di una chiara volonta&#8217; di imprimere una svolta seria alla condizione di precariato cui sono vincolati oltre seimila lavoratori calabresi da oltre quindici anni. Il Consiglio ha dato prova all&#8217;unanimita&#8217; di alto senso di responsabilita&#8217;, ma adesso &#8211; prosegue Nicolo&#8217; &#8211; occorre avviare tutte le iniziative necessarie, locali e nazionali, perche&#8217; si possano svuotare i bacini di precarieta&#8217;, aprendo una discussione seria con il futuro governo, l&#8217;Anci, i comuni e i sindacati, affinche&#8217;, ognuno per la propria parte di responsabilita&#8217;, contribuisca a favorire quei processi di stabilizzazione per porre fine ad una situazione umana e lavorativa deprimente che riguarda soprattutto molte famiglie disagiate. Il presidente Scopelliti ha posto con chiarezza la questione relativa alle risorse finanziarie, 21 milioni di euro per onorare i contratti Lpu-Lsu, che non possono essere a carico esclusivo della Regione. La spending-review, l&#8217;obbligo di rispettare l&#8217;equilibrio di bilancio pesano come una spada di Damocle sulle istituzioni democratiche&#8221;.Pur nella ristrettezza finanziaria &#8211; prosegue Alessandro Nicolo&#8217; &#8211; occorre promuovere quelle opportunita&#8217; affinche&#8217; si risolva questa piaga sociale. Senza un progetto politico-istituzionale unitario altrimenti ogni sforzo rischia di diventare vano in una situazione in cui il peso della crisi economica e del debito pubblico rischia di far precipitare una situazione di cui i primi destinatari sarebbero i precari e le loro famiglie. L&#8217;Assemblea &#8211; dice ancora Alessandro Nicolo&#8217; &#8211; ha saputo ritrovare inoltre quella grande unita&#8217; necessaria anche per affrontare il precariato nella sanita&#8217;, assicurando i livelli essenziali di assistenza in tutti i presidi ospedalieri della Regione. Nonostante i limiti e le difficolta&#8217; rinvenienti dal piano di rientro, il Consiglio regionale, dopo un dibattito arricchito dei contributi di tutti i gruppi politici. Un passaggio delicato, frutto di un attento lavoro di valutazione della terza Commissione consiliare e degli Uffici del Consiglio regionale con l&#8217;obiettivo di eliminare o affievolire drasticamente i profili di illegittimita&#8217; costituzionale che, di fatto, avevano sinora impedito la felice conclusione della vicenda&#8221;.<\/p>\n<p><strong>I precari Lsu-Lpu: &#8220;Siamo stanchi di precariet\u00e0 e norme transitorie. Vogliamo solo la normalit\u00e0&#8221;.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; REGGIO CALABRIA &#8211; &#8220;Salvaguardati i lavoratori essenziale per il funzionamento degli enti&#8221;. Approvata la legge del consiglio regionale che consente di colmare il vuoto legislativo<\/p>\n","protected":false},"author":22,"featured_media":19941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-19940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=19940"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/19940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/19941"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=19940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=19940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=19940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}