{"id":199400,"date":"2023-04-07T10:57:41","date_gmt":"2023-04-07T08:57:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=199400"},"modified":"2023-04-07T11:57:03","modified_gmt":"2023-04-07T09:57:03","slug":"arbitri-aggrediti-12-provvedimenti-daspo-dopo-due-incontri-di-calcio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/arbitri-aggrediti-12-provvedimenti-daspo-dopo-due-incontri-di-calcio\/","title":{"rendered":"Arbitri aggrediti, 12 provvedimenti Daspo dopo due incontri di calcio"},"content":{"rendered":"<p>VIBO VALENTIA &#8211; Arbitri aggrediti, arrivano le misure. Nel quadro delle attivit\u00e0 finalizzate a contrastare episodi di violenza in occasione di manifestazioni sportive, infatti, il questore di Vibo ha emesso <strong>12 provvedimenti<\/strong> di Divieto ad assistere a manifestazioni sportive a seguito di alcuni episodi di violenza che si sono verificati durante due incontri di calcio.<\/p>\n<h3>Arbitri aggrediti, i provvedimenti di Daspo<\/h3>\n<p>Il primo caso riguarda la gara tra <strong>l&#8217;a.g.s.d. Soriano 2010 e Compr. Capo vaticano<\/strong>, valevole per il campionato regionale juniores under 19 svoltasi lo <strong>scorso 24 gennaio<\/strong>. A seguito di una decisione dell\u2019arbitro, lo stesso era stato aggredito e costretto ad interrompere la gara. Per questo episodio sono stati eseguiti 8 provvedimenti Daspo per la durata di 3 anni nei confronti di<strong> 8 calciatori<\/strong> della a.g.s.d. Soriano 2010 under 19, che con la loro condotta si sono resi responsabili di atti di violenza e di intimidazione nei confronti del direttore di gara.<\/p>\n<p>Durante la gara tra la <strong>Crissense e il Real Fabriziese<\/strong>, valevole per il campionato di terza categoria, svoltasi lo scorso 5 febbraio 2023, a seguito di un provvedimento dell\u2019arbitro, si verificavano atti di violenza che hanno coinvolto calciatori e dirigenti, per cui l\u2019arbitro, impossibilitato a riprendere la gara ne decretava la fine. In tal caso sono stati emessi Daspo per la durata di 3 anni nei confronti di <strong>2 calciatori<\/strong> e un <strong>dirigente<\/strong> della Crissense, e per un <strong>giocatore<\/strong> del Real Fabriziese.<\/p>\n<p>I provvedimenti del questore, scaturiti a seguito di accertamenti svolti dalla <a href=\"https:\/\/www.poliziadistato.it\/articolo\/digos\" rel=\"noopener\">Digos<\/a> in stretta collaborazione con la divisione anticrimine della questura, sono stati adottati anche al fine di scongiurare ulteriori episodi di violenza nell\u2019ambito delle competizioni sportive.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIBO VALENTIA &#8211; Arbitri aggrediti, arrivano le misure. Nel quadro delle attivit\u00e0 finalizzate a contrastare episodi di violenza in occasione di manifestazioni sportive, infatti, il questore di Vibo ha emesso 12 provvedimenti di Divieto ad assistere a manifestazioni sportive a seguito di alcuni episodi di violenza che si sono verificati durante due incontri di calcio. [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":199401,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-199400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/199400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=199400"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/199400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/199401"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=199400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=199400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=199400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}