{"id":199718,"date":"2023-04-15T20:00:14","date_gmt":"2023-04-15T18:00:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=199718"},"modified":"2023-04-15T13:13:36","modified_gmt":"2023-04-15T11:13:36","slug":"emergenza-pronto-soccorso-il-ministro-schillaci-assicura-azioni-concrete","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/emergenza-pronto-soccorso-il-ministro-schillaci-assicura-azioni-concrete\/","title":{"rendered":"Emergenza pronto soccorso, il ministro Schillaci assicura \u00abazioni concrete\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Il sovraffollamento dei pronto soccorso \u00e8 il sintomo di una malattia pi\u00f9 grande che possiamo fermare solo attraverso azioni concrete e strutturali&#8221;. E su questo &#8220;si sta facendo finalmente qualcosa&#8221;. Lo ha detto il <strong>ministro della Salute, Orazio Schillaci,<\/strong> rispondendo ad una interrogazione a risposta immediata alla Camera.<\/p>\n<p>&#8220;Abbiamo trovato una sanit\u00e0 ingolfata e piena di contraddizioni, ha detto il ministro &#8211; abbiamo sentito chiamare i medici eroi, ma senza che si tenesse conto delle loro grida di dolore&#8221;. &#8220;<strong>La strada che stiamo intraprendendo ci sembra quella giusta, senza promettere miracoli irrealizzabil<\/strong>i, senza alimentare cooperative e senza distogliere risorse al sistema pubblico, a cui ha pensato ampiamente qualcuno, nel passato&#8221;. &#8220;Il fatto che il 70% degli accessi in pronto soccorso sia codice bianco o verde &#8211; ha sottolineato &#8211; significa che i cittadini hanno perso punti di riferimento sul territorio&#8221;.<\/p>\n<p>Proprio per questo &#8220;<strong>la medicina territoriale sar\u00e0 potenziata<\/strong>. Il PNRR stanzia fondi per le opere infrastrutturali, noi stiamo lavorando per rendere questi luoghi delle vere case della comunit\u00e0 a cui rivolgersi per visite, accertamenti e servizi sanitari preventivi&#8221;.<\/p>\n<p><strong> Con il decreto legge 34, infatti &#8220;abbiamo innalzato i compensi per i medici che lavorano in emergenza urgenza da 60 a 100 euro orari<\/strong>, <strong>abbiamo disposto aumenti per gli infermieri e anticipato le indennit\u00e0 di pronto soccorso senza attendere il 2024.<\/strong> Prevediamo poi assunzioni anche senza specializzazione diretta e contratti libero professionali per gli specializzandi&#8221;. &#8220;Sostenere economicamente la professione medica &#8211; ha concluso &#8211; \u00e8 fondamentale per riconoscere davvero quegli eroi che si occupano quotidianamente del valore pi\u00f9 importante: la nostra Salute&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Il sovraffollamento dei pronto soccorso \u00e8 il sintomo di una malattia pi\u00f9 grande che possiamo fermare solo attraverso azioni concrete e strutturali&#8221;. E su questo &#8220;si sta facendo finalmente qualcosa&#8221;. Lo ha detto il ministro della Salute, Orazio Schillaci, rispondendo ad una interrogazione a risposta immediata alla Camera. &#8220;Abbiamo trovato una sanit\u00e0 ingolfata [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":193653,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-199718","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/199718","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=199718"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/199718\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/193653"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=199718"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=199718"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=199718"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}