{"id":200557,"date":"2023-04-25T12:52:50","date_gmt":"2023-04-25T10:52:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=200557"},"modified":"2023-04-25T12:52:50","modified_gmt":"2023-04-25T10:52:50","slug":"belvedere-marittimo-la-denuncia-sversamenti-di-liquami-intervenga-la-procura","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/belvedere-marittimo-la-denuncia-sversamenti-di-liquami-intervenga-la-procura\/","title":{"rendered":"Belvedere marittimo, la denuncia: \u00absversamenti di liquami, intervenga la Procura\u00bb"},"content":{"rendered":"<p>BELVEDERE MARITTIMO (CS) &#8211;<strong> Il gruppo consiliare Impegno Comune, denuncia possibili sversamenti nella zona di Belvedere Marittimo<\/strong>. Cosi dichiara \u201cAbbiamo portato all\u2019attenzione dell\u2019amministrazione comunale la possibilit\u00e0 di porre fine alle disfunzioni funzionali delle <strong>fognatura comunale<\/strong> nel tratto di area urbana, adiacente all ss 18, compreso<strong> fra il torrente Vallecupo e lo svincolo nord della ss. 18<\/strong> di localit\u00e0 Vetticello, gi\u00e0 oggetto di una nostra segnalazione in data 31 Dicembre 2022.<\/p>\n<p>Si tratta di una soluzione poi proposta all\u2019ente in data 20 Febbraio 2023. Ad <strong>un problema atavico che la maggioranza non pu\u00f2 non tenere in considerazione<\/strong>. Alla luce di queste dichiarazioni, intervenga senza indugio la procura della Repubblica di Paola, coadiuvati dal comando dei carabinieri del nipaf\u00a0 e dall\u2019Arpacal guidata dal Generale Emilio Errigo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BELVEDERE MARITTIMO (CS) &#8211; Il gruppo consiliare Impegno Comune, denuncia possibili sversamenti nella zona di Belvedere Marittimo. Cosi dichiara \u201cAbbiamo portato all\u2019attenzione dell\u2019amministrazione comunale la possibilit\u00e0 di porre fine alle disfunzioni funzionali delle fognatura comunale nel tratto di area urbana, adiacente all ss 18, compreso fra il torrente Vallecupo e lo svincolo nord della ss. [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":200561,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-200557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=200557"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200557\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/200561"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=200557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=200557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=200557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}