{"id":200774,"date":"2023-04-29T07:47:03","date_gmt":"2023-04-29T05:47:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=200774"},"modified":"2023-04-29T07:47:28","modified_gmt":"2023-04-29T05:47:28","slug":"manca-in-tutta-italia-lamoxicillina-antibiotico-per-bimbi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/manca-in-tutta-italia-lamoxicillina-antibiotico-per-bimbi\/","title":{"rendered":"Manca in tutta Italia l&#8217;amoxicillina, antibiotico per bimbi"},"content":{"rendered":"<p>ROMA &#8211; <strong>\u00c8\u00a0carente in tutta Italia, da alcune settimane, l&#8217;antibiotico amoxicillina,<\/strong> appartenente alla famiglia delle penicilline e <strong>utilizzato contro varie malattie infettive nei bambini<\/strong>,<strong> dalla scarlattina all&#8217;infezione da streptococco di tipo A.<\/strong> Il farmaco \u00e8 infatti indicato nella lista di quelli attualmente carenti, pubblicata sul sito dell&#8217;Agenzia italiana del farmaco (Aifa). L&#8217;amoxicillina risulta non disponibile per varie tipologie ed aziende produttrici.<\/p>\n<p>Per alcuni formati la data di fine carenza \u00e8 indicata entro la fine di maggio ma per altre tipologie bisogner\u00e0 attendere anche <strong>oltre l&#8217;estate per un ritorno alla piena disponibilit\u00e0.<\/strong> Quanto ai motivi della carenza, l&#8217;Aifa ne indica vari: l&#8217;elevata richiesta, problemi produttivi, la cessata commercializzazione temporanea o forniture discontinue. Sono comunque disponibili dei farmaci equivalenti a questo antibiotico: per i trattamenti alternativi, l&#8217;Aifa consiglia di rivolgersi allo specialista o al medico di medicina generale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; \u00c8\u00a0carente in tutta Italia, da alcune settimane, l&#8217;antibiotico amoxicillina, appartenente alla famiglia delle penicilline e utilizzato contro varie malattie infettive nei bambini, dalla scarlattina all&#8217;infezione da streptococco di tipo A. Il farmaco \u00e8 infatti indicato nella lista di quelli attualmente carenti, pubblicata sul sito dell&#8217;Agenzia italiana del farmaco (Aifa). L&#8217;amoxicillina risulta non disponibile [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":120810,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-200774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=200774"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/120810"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=200774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=200774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=200774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}