{"id":200870,"date":"2023-05-02T07:44:06","date_gmt":"2023-05-02T05:44:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=200870"},"modified":"2023-05-02T07:44:22","modified_gmt":"2023-05-02T05:44:22","slug":"giovane-muore-incidente-dolore-e-cordoglio-a-san-marco-argentano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/giovane-muore-incidente-dolore-e-cordoglio-a-san-marco-argentano\/","title":{"rendered":"Giovane muore in un incidente, dolore e cordoglio a San Marco Argentano"},"content":{"rendered":"<p>SAN MARCO ARGENTANO (CS) &#8211; La comunit\u00e0 di San Marco Argentano scossa dal terribile <a href=\"https:\/\/quicosenza.it\/news\/provincia\/tragico-incidente-tra-mongrassano-e-san-marco-argentano-morto-un-giovane-di-23-anni\">incidente stradale<\/a> che ieri ha strappato alla vita il 23enne Manuel Ricioppo. Il sindaco, Virginia Mariotti, ha espresso cordoglio e in un post su Facebook sottolinea come il \u00abgravissimo incidente ha rattristato San Marco in una giornata di festa\u00bb.<\/p>\n<p>\u00abA nome della Citt\u00e0 e mio personale esprimo profondo cordoglio alle famiglie Ricioppo- Antonucci per la tragica <strong>scomparsa del giovane Manuel<\/strong>. In questo momento di immensa tristezza e di straziante dolore sento il bisogno di <strong>abbracciare forte la famiglia di Manuel<\/strong>, il pap\u00e0 Delfino, il fratello Jonathan, gli zii, i cugini e gli amici tutti, perch\u00e9 sentano il conforto e la vicinanza di tutta la comunit\u00e0. Resteranno nella nostra memoria la simpatia e l\u2019affabilit\u00e0 di Manuel, nella certezza che da oggi,<strong> lass\u00f9 in cielo, un altro angelo veglier\u00e0 su tutti noi\u00bb.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAN MARCO ARGENTANO (CS) &#8211; La comunit\u00e0 di San Marco Argentano scossa dal terribile incidente stradale che ieri ha strappato alla vita il 23enne Manuel Ricioppo. Il sindaco, Virginia Mariotti, ha espresso cordoglio e in un post su Facebook sottolinea come il \u00abgravissimo incidente ha rattristato San Marco in una giornata di festa\u00bb. \u00abA nome [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":200871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-200870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=200870"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/200871"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=200870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=200870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=200870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}