{"id":200934,"date":"2023-05-02T17:11:11","date_gmt":"2023-05-02T15:11:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=200934"},"modified":"2023-05-02T17:39:12","modified_gmt":"2023-05-02T15:39:12","slug":"ospedale-di-rogliano-riapre-dopo-tre-anni-il-centro-dialisi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ospedale-di-rogliano-riapre-dopo-tre-anni-il-centro-dialisi\/","title":{"rendered":"Ospedale di Rogliano, riapre dopo tre anni il Centro Dialisi"},"content":{"rendered":"<p>ROGLIANO (CS) &#8211; &#8220;Aggiungiamo un altro tassello <strong>nel percorso di crescita gi\u00e0 avviato da questa Azienda<\/strong> e fortemente voluto e sostenuto dal Presidente della Regione, Roberto Occhiuto&#8221;. E\u2019 con viva soddisfazione che oggi, <strong>finalmente a distanza di circa tre anni, annunciamo la riapertura del Centro Dialisi nell\u2019Ospedale Santa Barbara di Rogliano<\/strong>\u201d.<\/p>\n<p>Queste le parole del Commissario Straordinario dell\u2019<strong>Asp di Cosenza Dottor Antonio Graziano<\/strong>. Il reparto, si presenta completamente ristrutturato, pronto ad accogliere le richieste dei cittadini <strong>con attrezzature mediche di ultima generazione, nuovi reni artificiali e letti\/bilancia elettrici<\/strong>. \u201cTrattandosi di pazienti che meritano grande attenzione, riteniamo di aver restituito al territorio del<strong> Savuto un servizio fondamentale che consentir\u00e0 di eliminare la continua, costante e complicata migrazione verso altri Centri della provincia cosentina<\/strong>\u201d. Il nuovo reparto, ospiter\u00e0 fino a otto posti rene che consentiranno al momento la ricezione di sedici pazienti su due turni giornalieri<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROGLIANO (CS) &#8211; &#8220;Aggiungiamo un altro tassello nel percorso di crescita gi\u00e0 avviato da questa Azienda e fortemente voluto e sostenuto dal Presidente della Regione, Roberto Occhiuto&#8221;. E\u2019 con viva soddisfazione che oggi, finalmente a distanza di circa tre anni, annunciamo la riapertura del Centro Dialisi nell\u2019Ospedale Santa Barbara di Rogliano\u201d. Queste le parole del [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":200935,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-200934","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=200934"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/200934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/200935"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=200934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=200934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=200934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}