{"id":20124,"date":"2013-03-25T16:40:15","date_gmt":"2013-03-25T15:40:15","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20124"},"modified":"2023-01-17T13:17:56","modified_gmt":"2023-01-17T12:17:56","slug":"7584-bergamini-si-aggrava-la-posizione-della-ex","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7584-bergamini-si-aggrava-la-posizione-della-ex\/","title":{"rendered":"Bergamini, si aggrava la posizione della ex"},"content":{"rendered":"<div class=\"Paragraph\" style=\"margin-bottom: 10px; color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 13px; line-height: 16px; background-color: #ffffff; text-align: justify;\"><strong>CASTROVILLARI (CS)<\/strong> &#8211; Il giallo della morte dell&#8217; ex calciatore del Cosenza, Donato Bergamini, sembra stia giungendo al termine.&nbsp;La Procura di Castrovillari<\/div>\n<p>  <!--more-->  <\/p>\n<div class=\"Paragraph\" style=\"margin-bottom: 10px; color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 13px; line-height: 16px; background-color: #ffffff; text-align: justify;\">avrebbe infatti i nomi dei presunti assassini. Una notizia che attende per\u00f2 diverse conferme.&nbsp;Certo \u00e8 che il cerchio si sta stringendo.<span style=\"font-size: 13px; background-color: #ffffff;\"> La famiglia Bergamini e l\u2019avvocato Eugenio Gallerani, ospiti a &#8220;Chi l\u2019ha visto?&#8221; , &nbsp;aveva fatto notare le incongruenze del cronotachigrafo, la &#8220;scatola nera&#8221; del camion che avrebbe investito il suicida Denis (espressione ormai passata) quel maledetto<\/span><span style=\"font-size: 13px; background-color: #ffffff;\">&nbsp;<\/span>18 novembre 1989.&nbsp;<\/div>\n<div class=\"Paragraph\" style=\"margin-bottom: 10px; color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 13px; line-height: 16px; background-color: #ffffff; text-align: justify;\"><span style=\"font-size: 13px; background-color: #ffffff;\"><\/span><span style=\"font-size: 13px; background-color: #ffffff;\"><\/span>Raffaele Pisano per\u00f2, alla guida della vettura,<span style=\"font-size: 13px; background-color: #ffffff;\">&nbsp;<\/span><span style=\"font-size: 13px; background-color: #ffffff;\">all\u2019epoca dichiar\u00f2 alla magistratura di essere partito da Rosarno, distante circa 224 chilometri dal presunto luogo dell\u2019incidente a Roseto Capo Spulico. Tra i dati inseriti figurano 177 chilometri percorsi, non figura la targa del veicolo e soprattutto nella trascrizione della data &#8220;18\/11\/89&#8221;, le cifre indicanti il giorno e il mese appaiono scritte con diverse grafie.<\/span><span style=\"font-size: 13px; background-color: #ffffff;\">&nbsp;<\/span><span style=\"font-size: 13px; background-color: #ffffff;\">In particolare la grafia che riporta il mese di novembre \u00e8 segnata con due linee verticali (11), mentre in quella che indica il giorno esatto, 18, il numero 1 \u00e8 composto anche dalla piccola linea obliqua in cima. E come se non bastasse gli inquirenti hanno rilevato tracce di sangue su un lato del veicolo, quando invece il presunto impatto sarebbe stato frontale.<\/span><\/div>\n<div class=\"Paragraph\" style=\"margin-bottom: 10px; color: #000000; font-family: Arial, Helvetica, sans-serif; font-size: 13px; line-height: 16px; background-color: #ffffff; text-align: justify;\"><span style=\"font-size: 13px; background-color: #ffffff;\"><\/span><span style=\"font-size: 13px; background-color: #ffffff;\">Pi\u00f9 che mai in bilico, dunque, la posizione di Isabella Intern\u00f2, ex fidanzata dell&#8217;epoca di Bergamini, sulla cui testimonianza oculare si \u00e8 retta la tesi iniziale del suicidio.<\/span><span style=\"font-size: 13px; background-color: #ffffff;\">&nbsp;<\/span><span style=\"font-size: 13px; background-color: #ffffff;\">Dalla<\/span><span style=\"cursor: pointer;\">&nbsp;riapertura del caso, avvenuta nel giugno del 2011<\/span><span style=\"font-size: 13px; background-color: #ffffff;\">, sta uscendo fuori ben altra verit\u00e0. Sono troppi gli elementi che fanno pensare all\u2019omicidio. Un omicidio che secondo l\u2019autorevole giornalista d\u2019inchiesta Gabriele Carchidi (fondamentale con la sua campagna stampa e pi\u00f9 volte intervistato dai media nazionali) presumibilmente \u00e8 stato compiuto da pi\u00f9 di una persona, con l\u2019assenso e forse la complicit\u00e0 della \u2018ndrangheta. La palla \u00e8 in mano al procuratore capo di Castrovillari Franco Giacomantonio.<\/span><\/div>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Il giallo della morte dell&#8217; ex calciatore del Cosenza, Donato Bergamini, sembra stia giungendo al termine.&nbsp;La Procura di Castrovillari<\/p>\n","protected":false},"author":22,"featured_media":20125,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,20],"tags":[],"class_list":["post-20124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20124"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20125"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}