{"id":20141,"date":"2013-03-26T08:59:20","date_gmt":"2013-03-26T07:59:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20141"},"modified":"2023-01-17T13:17:58","modified_gmt":"2023-01-17T12:17:58","slug":"7593-azienda-truffa-66-dipendenti-e-neanche-un-macchinario","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7593-azienda-truffa-66-dipendenti-e-neanche-un-macchinario\/","title":{"rendered":"Azienda truffa, 66 dipendenti e neanche un macchinario"},"content":{"rendered":"<p><p><span style=\"font-size: 12px; line-height: 1;\">REGGIO CALABRIA &#8211; Un&#8217;azienda agricola che produceva olio fantasma.<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 12px; line-height: 1;\">E&#8217; stato rilevato che i terreni agricoli, localizzati nei comuni di Roccella Jonica, Locri, Martone, Portigliola e Gioiosa Jonica della provincia di Reggio Calabria, sono risultati incolti e, ormai da diverso tempo, in totale stato di abbandono. Inoltre, il titolare dell&#8217;azienda, che non possiede macchine agricole, n\u00e8 strumenti per la coltivazione dei terreni, non ha saputo fornire elementi circa i rapporti di lavoro instaurati con i propri dipendenti, n\u00e8 presso quali frantoi avesse effettuato la molitura delle olive. Dalle indagini \u00e8 emerso che il titolare dell&#8217;azienda ha emesso fatture relative ad operazioni inesistenti nei confronti di ignari clienti, aventi ad oggetto la vendita di olio d&#8217;oliva, i quali hanno disconosciuto i documenti contabili. Inoltre, la costituzione fraudolenta di tali rapporti di lavoro ha fatto nascere il diritto a percepire future prestazioni pensionistiche da parte dei lavoratori fittizi, andando cosi&#8217; ad appesantire ulteriormente le casse dello Stato. Sono stati denunciati alla Procura della Repubblica di Locri il titolare dell&#8217;impresa jonica e i 66 braccianti per concorso in truffa aggravata ai danni dell&#8217;I.N.P.S.. Le persone sono state segnalate anche alla Procura Regionale della Corte dei Conti per il danno erariale causato dalla indebita percezione delle indennita&#8217;.&nbsp;<\/span><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA &#8211; Un&#8217;azienda agricola che produceva olio fantasma.<\/p>\n","protected":false},"author":22,"featured_media":20142,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-20141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20141"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20141\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20142"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}