{"id":201412,"date":"2023-05-08T21:00:53","date_gmt":"2023-05-08T19:00:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=201412"},"modified":"2023-05-08T19:31:31","modified_gmt":"2023-05-08T17:31:31","slug":"castrovillari-anas-non-risponde-laghi-presenta-interrogazione-sulle-indicazioni-stradali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/castrovillari-anas-non-risponde-laghi-presenta-interrogazione-sulle-indicazioni-stradali\/","title":{"rendered":"Castrovillari: \u00abAnas non risponde. Laghi presenta interrogazione sulle indicazioni stradali\u00bb"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Dopo lunghe attese e la scortesia di una mancata risposta da parte di Anas, il capogruppo in Consiglio regionale di &#8220;De Magistris Presidente&#8221;, <strong>Ferdinando Laghi,<\/strong> ha presentato una Interrogazione a risposta scritta<strong> &#8220;in merito alle condizioni della segnaletica nel tratto stradale e autostradale che conduce alla citt\u00e0 di Castrovillari&#8221;<\/strong>. Il tutto a seguito di un&#8217;operazione avviata lo scorso 5 novembre 2022, quando si \u00e8 proceduto a interessar<strong>e la Provincia di Cosenza, relativamente al tratto di competenza, nonch\u00e9 la sezione Anas Spa<\/strong> competente per territorio, per il tratto autostradale di riferimento.<\/p>\n<p>\u00abCon la Provincia di Cosenza &#8211;<strong>scrive il Consigliere Laghi<\/strong>&#8211; si sono tenuti degli incontri istituzionali sottesi alla pronta e rapida risoluzione della problematica, per cui a stretto giro si cantiereranno i relativi lavori\u00bb. <strong>Nello stesso documento il consigliere Sottolinea che: \u00abnonostante reiterati solleciti (il primo in data 20.02.2023; il secondo, rivolto anche alla sezione regionale nonch\u00e9 alla direzione nazionale, in data 14.04.2023) l&#8217;Anas Spa \u00e8 rimasta silente<\/strong>\u00bb. L&#8217;obiettivo esplicito \u00e8 chiaro e riguarda la tutela della sicurezza stradale oltre a evitare disservizi alla circolazione (lavoratori, vettori, turisti, automobilisti in genere).<\/p>\n<p>Alla luce di quanto sta accadendo, Laghi precisa che \u00abrisulta urgente e improcrastinabile un intervento istituzionale sotteso alla interlocuzione con Anas Spa, funzionale all&#8217;adeguamento della<strong> cartellonistica stradale, sia orizzontale che verticale, idonea al raggiungimento della Citt\u00e0 di Castrovillari<\/strong>\u00bb. Per tali ragioni, quindi, s&#8217;interroga la Giunta regionale per sapere: \u00abQuali iniziative intenda assumere per garantire la funzionale presenza di adeguata <strong>segnaletica stradale nel tratto di riferimento sopra indicato; quali iniziative sono state, o saranno, assunte al fine di garantire un&#8217;adeguata segnaletica stradale<\/strong> su tutto il territorio regionale, sia di competenza delle singole province che di competenza di Anas Spa\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Dopo lunghe attese e la scortesia di una mancata risposta da parte di Anas, il capogruppo in Consiglio regionale di &#8220;De Magistris Presidente&#8221;, Ferdinando Laghi, ha presentato una Interrogazione a risposta scritta &#8220;in merito alle condizioni della segnaletica nel tratto stradale e autostradale che conduce alla citt\u00e0 di Castrovillari&#8221;. Il tutto a [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":191257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-201412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=201412"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/191257"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=201412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=201412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=201412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}