{"id":201440,"date":"2023-05-09T06:37:21","date_gmt":"2023-05-09T04:37:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=201440"},"modified":"2023-05-09T10:42:44","modified_gmt":"2023-05-09T08:42:44","slug":"droga-ed-estorsioni-blitz-dei-carabinieri-tra-paola-e-san-lucido-37-misure-cautelari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/droga-ed-estorsioni-blitz-dei-carabinieri-tra-paola-e-san-lucido-37-misure-cautelari\/","title":{"rendered":"Droga ed estorsioni: blitz dei carabinieri tra Paola e San Lucido, 37 misure cautelari"},"content":{"rendered":"<p>COSENZA &#8211; E&#8217; scattata questa mattina un&#8217;operazione dei carabinieri del Comando Provinciale di Cosenza tra Paola e San Lucido, sul Tirreno cosentino, coordinata dalla Dda di Catanzaro. Eseguite <strong>37 misure<\/strong> cautelari nei confronti di altrettanti indagati, accusati a vario titolo di associazione di tipo mafioso, <strong>estorsione<\/strong> e tentata estorsione aggravata, <strong>trasferimento fraudolento di valori<\/strong>, detenzione e porto illegale di <strong>arma<\/strong> comune da sparo, nonch\u00e9 associazione finalizzata al traffico di <strong>sostanze stupefacenti<\/strong>, detenzione ai fini di spaccio di sostanze stupefacenti (hashish, marijuana e cocaina) in concorso, anche aggravati dalle modalit\u00e0 e finalit\u00e0 mafiose e altri reati.<\/p>\n<p>Sono <strong>18 i soggetti finiti in carcere<\/strong> mentre per gli altri indagati le misure vanno dagli arresti domiciliari all&#8217;obbligo di dimora. Dalle indagini \u00e8 emersa l&#8217;operativit\u00e0 dei clan Calabria e Tundis nelle due citt\u00e0 tirreniche, e anche a Belmonte e Longobardi. Le 18 persone raggiunta dalla misura detentiva in carcere sono Andrea Al\u00f2, Gianluca Arlia, Luciano Bruno, Fabio Calabria, Giuseppe Calabria, Pietro Calabria, Salvatore Caruso, Michele Iannelli, Giuseppe La Rosa, Eugenio Logatto, Mario Maiolo, Marco Manfredi, Gabriele Molinaro, Roberto Porcaro, Andrea Tundis, Emanuele Tundis, Michele Tundis e Pamela Villecco. <strong>Ai domiciliari<\/strong> invece sono stati assegnati Raffaele Conforti; Paolo D&#8217;Amato, Giovanni Fiore, Giovanni Garofalo, Vincenzo Nesci, Cristian Vommaro e Francesco Serpa.<\/p>\n<p>Sono 9 le misure cautelari di obbligo di dimora o presentazione alla Polizia giudiziaria, un divieto di dimora e due persone sono state interdette dall&#8217;esercizio dell&#8217;attivit\u00e0 imprenditoriale. Tra le persone raggiunte dalla misura in carcere anche il presunto boss Roberto Porcaro che da qualche tempo starebbe collaborando con i magistrati antimafia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; E&#8217; scattata questa mattina un&#8217;operazione dei carabinieri del Comando Provinciale di Cosenza tra Paola e San Lucido, sul Tirreno cosentino, coordinata dalla Dda di Catanzaro. Eseguite 37 misure cautelari nei confronti di altrettanti indagati, accusati a vario titolo di associazione di tipo mafioso, estorsione e tentata estorsione aggravata, trasferimento fraudolento di valori, detenzione [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":201459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-201440","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201440","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=201440"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201440\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/201459"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=201440"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=201440"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=201440"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}