{"id":201559,"date":"2023-05-10T11:45:18","date_gmt":"2023-05-10T09:45:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=201559"},"modified":"2023-05-10T11:45:18","modified_gmt":"2023-05-10T09:45:18","slug":"lotto-a-corigliano-rossano-vinti-oltre-40mila-euro","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lotto-a-corigliano-rossano-vinti-oltre-40mila-euro\/","title":{"rendered":"Lotto, a Corigliano Rossano vinti oltre 40mila euro"},"content":{"rendered":"<p>COSENZA &#8211; Il lotto premia nuovamente la Calabria e nell\u2019ultimo concorso, secondo quanto riporta Agipronews, sono arrivate vincite complessive per 80 mila euro. Arriva da <strong>Corigliano Rossano<\/strong>, in provincia di Cosenza, la pi\u00f9 alta dell&#8217;ultimo concorso: nella localit\u00e0 jonica del Cosentino, sono stati vinti 40.750 euro con la combinazione 65-80-88 sulla ruota di Cagliari.<\/p>\n<p>Sono altre due le vincite realizzate in Calabria: la prima, da 25.350, \u00e8 arrivata a <strong>Catanzaro<\/strong> con i numeri 26-28-47-51 giocati su tutte le ruote, mentre la seconda \u00e8 da segnalare a Siderno, in provincia di <strong>Reggio Calabria<\/strong>, per un valore di 14mila euro. L&#8217;ultimo concorso del Lotto ha distribuito 5,2 milioni di euro, per un totale di 414 milioni da inizio anno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Il lotto premia nuovamente la Calabria e nell\u2019ultimo concorso, secondo quanto riporta Agipronews, sono arrivate vincite complessive per 80 mila euro. Arriva da Corigliano Rossano, in provincia di Cosenza, la pi\u00f9 alta dell&#8217;ultimo concorso: nella localit\u00e0 jonica del Cosentino, sono stati vinti 40.750 euro con la combinazione 65-80-88 sulla ruota di Cagliari. Sono [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":114017,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[],"class_list":["post-201559","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=201559"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201559\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/114017"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=201559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=201559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=201559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}