{"id":201580,"date":"2023-05-10T13:54:21","date_gmt":"2023-05-10T11:54:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=201580"},"modified":"2023-05-10T13:54:21","modified_gmt":"2023-05-10T11:54:21","slug":"crollo-quarto-lotto-della-sila-mare-gdf-acquisisce-documenti-in-regione-e-anas","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/crollo-quarto-lotto-della-sila-mare-gdf-acquisisce-documenti-in-regione-e-anas\/","title":{"rendered":"Crollo quarto lotto della Sila Mare, Gdf acquisisce documenti in Regione e Anas"},"content":{"rendered":"<p>CATANZARO &#8211; I militari del Nucleo di Polizia economico-finanziaria della Guardia &#8211; Gruppo tutele spesa pubblica &#8211; sezione anticorruzione di Catanzaro in mattinata hanno acquisito, negli uffici del Dipartimento<strong> Infrastrutture e lavori pubblici della Regione Calabria e della Struttura territoriale Calabria dell&#8217;Anas di Catanzaro, atti e documenti inerenti al crollo di parte del viadotto &#8220;Ortiano 2&#8221;,<\/strong> avvenuto il 3 maggio scorso sulla statale 117dir di Longobucco conosciuta anche come &#8220;Sila-Mare&#8221;.<\/p>\n<p>I finanzieri hanno avviato l&#8217;indagine su delega dalla Procura regionale presso la sezione giurisdizionale della <strong>Corte dei conti di Catanzaro che intende verificare eventuali danni erariali in relazione alla costruzione del viadotto crollato in seguito alla piena del fiume Trionto<\/strong>. Il viadotto era stato aperto al traffico dalla Regione Calabria nel 2016 e la gestione dell&#8217;opera era passata in capo all&#8217;Anas dal 2019. <strong>Le acquisizioni documentali negli uffici di Regione, Anas e di eventuali altri enti pubblici interessati alla realizzazione e gestione dell&#8217;opera,<\/strong> riguarderanno la documentazione relativa alla realizzazione del viadotto attraverso la quale ricostruire la procedura seguita all&#8217;affidamento dei lavori, il contratto sottoscritto per l&#8217;esecuzione dell&#8217;opera, le figure di riferimento come Rup e progettista e direttore dei lavori, la documentazione sul collaudo e quella sui costi complessivi sostenuti dall&#8217;amministrazione appaltante, gli atti di affidamento della gestione all&#8217;Anas e i controlli effettuati fino ad oggi.<\/p>\n<p>Saranno possibili audizioni di amministratori, dirigenti e funzionari degli enti interessati e anche soggetti privati in possesso di informazioni utili e di interesse. <strong>Sulla vicenda del crollo la Procura di Castrovillari, gi\u00e0 all&#8217;indomani del cedimento del viadotto, ha avviato un&#8217;indagine penale<\/strong> distinta da quella della magistratura contabile.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; I militari del Nucleo di Polizia economico-finanziaria della Guardia &#8211; Gruppo tutele spesa pubblica &#8211; sezione anticorruzione di Catanzaro in mattinata hanno acquisito, negli uffici del Dipartimento Infrastrutture e lavori pubblici della Regione Calabria e della Struttura territoriale Calabria dell&#8217;Anas di Catanzaro, atti e documenti inerenti al crollo di parte del viadotto &#8220;Ortiano [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":201053,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-201580","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=201580"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/201053"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=201580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=201580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=201580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}