{"id":20175,"date":"2013-03-26T13:33:20","date_gmt":"2013-03-26T12:33:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20175"},"modified":"2023-01-17T13:17:59","modified_gmt":"2023-01-17T12:17:59","slug":"7611-psioriasi-spot-pubblicitario-con-maria-grazia-cucinotta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7611-psioriasi-spot-pubblicitario-con-maria-grazia-cucinotta\/","title":{"rendered":"Psioriasi, spot pubblicitario con Maria Grazia Cucinotta"},"content":{"rendered":"<p><strong>ROMA<\/strong> &#8211; La psoriasi \u00e8 una malattia infiammatoria cronica della pelle, non infettiva n\u00e9 contagiosa, solitamente di carattere cronico e recidivante. Nella sua patogenesi intervengono fattori autoimmunitari, genetici e<\/p>\n<p>  <!--more-->  <\/p>\n<p>ambientali. Molti sono gli italiani affetti da questa malattia, tenuta sotto controllo grazie al lavoro del dermatologo. Vergognarsene non serve. E&#8217; il messaggio dello spot &#8216;Hai la psoriasi? Non nasconderti!&#8217;, con Maria Grazia Cucinotta testimonial, nell&#8217;ambito della Campagna &#8216;Che ne sai di psoriasi? Conoscerla per curarla&#8217; promossa dall&#8217;Associazione a Difesa degli Psoriasici. Lo spot sara&#8217; diffuso dal 28 marzo al 10 aprile in circa 500 cinema italiani<\/p>\n<p><div>&nbsp;<\/div><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; La psoriasi \u00e8 una malattia infiammatoria cronica della pelle, non infettiva n\u00e9 contagiosa, solitamente di carattere cronico e recidivante. Nella sua patogenesi intervengono fattori autoimmunitari, genetici e<\/p>\n","protected":false},"author":22,"featured_media":20176,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,34,52],"tags":[],"class_list":["post-20175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-magazine","category-salute-bellezza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20175"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20175\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20176"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}