{"id":201899,"date":"2023-05-15T06:35:47","date_gmt":"2023-05-15T04:35:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=201899"},"modified":"2023-05-15T06:37:07","modified_gmt":"2023-05-15T04:37:07","slug":"incidente-tra-due-auto-finisce-contro-il-muro-ferita-la-conducente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/incidente-tra-due-auto-finisce-contro-il-muro-ferita-la-conducente\/","title":{"rendered":"Incidente tra due auto, una finisce contro il muro. Ferita la conducente"},"content":{"rendered":"<p>CURINGA (CZ) &#8211; L&#8217;incidente si \u00e8 verificato ieri sera intorno alle 22, in localit\u00e0 Ponte Turrina tra Curinga e la frazione Acconia. Due le vetture coinvolte: una Fiat Panda ed un Suv SsangYong Rexton. A bordo della Panda la <strong>giovane conducente<\/strong> che \u00e8 stata estratta dall&#8217;abitacolo dai vigili del fuoco ed affidata al personale sanitario del 118 per le cure del caso. Successivamente \u00e8 stata portata in <strong>ospedale a Catanzaro<\/strong>. Sul posto i vigili del fuoco per mettere in sicurezza l&#8217;area dell&#8217;incidente e le vetture, e i carabinieri per gli adempimenti di competenza.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-201900 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02.jpg\" alt=\"incidente curinga vvff 02\" width=\"597\" height=\"370\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/05\/incidente-curinga-vvff-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 597px) 100vw, 597px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CURINGA (CZ) &#8211; L&#8217;incidente si \u00e8 verificato ieri sera intorno alle 22, in localit\u00e0 Ponte Turrina tra Curinga e la frazione Acconia. Due le vetture coinvolte: una Fiat Panda ed un Suv SsangYong Rexton. A bordo della Panda la giovane conducente che \u00e8 stata estratta dall&#8217;abitacolo dai vigili del fuoco ed affidata al personale sanitario [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":201901,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-201899","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201899","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=201899"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/201899\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/201901"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=201899"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=201899"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=201899"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}