{"id":20195,"date":"2013-03-26T15:48:37","date_gmt":"2013-03-26T14:48:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20195"},"modified":"2023-01-17T13:18:00","modified_gmt":"2023-01-17T12:18:00","slug":"7621-la-criminalita-tra-evasione-e-corruzione-costa-500-mld-allanno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7621-la-criminalita-tra-evasione-e-corruzione-costa-500-mld-allanno\/","title":{"rendered":"La criminalit\u00e0, tra evasione e corruzione, costa 500 mld all&#8217;anno"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>ROMA<\/strong> &#8211; In Italia le mafie gravano pesantemente sullo stato sottraendo quasi 500 miliardi di euro al Paese. La stima e&#8217; basata su una rielaborazione dei dati<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">ufficiali di alcuni istituti &#8211; quali la Banca d&#8217;Italia e l&#8217;Istat &#8211; realizzata da una serie di associazioni, tra cui Arci, Libera e Avviso Pubblico, che hanno presentato questa mattina a Roma la sedicesima edizione della Carovana Internazionale antimafie. Nel corso della presentazione sono anche stati divulgati gli ultimi dati dell&#8217;Agenzia nazionale per l&#8217;amministrazione e la destinazione dei beni sequestrati e confiscati alla criminalita&#8217; organizzata: al 7 gennaio scorso erano 12.946 i beni confiscati alle mafie. Di questi, 11.238 erano immobili e 1708 erano aziende. Ad aggiudicarsi il primato e&#8217; la Sicilia che conta 5515 beni confiscati (il 42,6 per cento del totale), seguita dalla Campania, con 1918 beni, dalla Calabria, con 1811 beni, dalla Lombardia, con 1186 beni, e dalla Puglia con 1126 beni.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; In Italia le mafie gravano pesantemente sullo stato sottraendo quasi 500 miliardi di euro al Paese. La stima e&#8217; basata su una rielaborazione dei dati<\/p>\n","protected":false},"author":22,"featured_media":20196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-20195","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20195","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20195"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20195\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20196"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20195"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20195"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20195"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}