{"id":202048,"date":"2023-05-16T16:14:56","date_gmt":"2023-05-16T14:14:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202048"},"modified":"2023-05-16T17:04:33","modified_gmt":"2023-05-16T15:04:33","slug":"decretocs-per-il-ponte-longobucco-no-della-camera-m5s-attacca-non-e-una-vostra-priorita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/decretocs-per-il-ponte-longobucco-no-della-camera-m5s-attacca-non-e-una-vostra-priorita\/","title":{"rendered":"Decreto per il ponte Longobucco: No della Camera. M5S attacca: \u00abnon \u00e8 una vostra priorit\u00e0\u00bb"},"content":{"rendered":"<p>ROMA &#8211; <strong>No della Camera a un ordine del giorno di M5s al decreto sul ponte sullo Stretto<\/strong> che impegnava il governo &#8220;a prevedere con urgenza, anche con un decreto legge ad hoc alla messa in sicurezza&#8221; della zona del <strong>crollo del viadotto del Comune di Longobucco<\/strong>.<\/p>\n<p>Via libera, invece, a un <strong>odg della Lega che impegna il governo &#8220;a monitorare gli esiti degli accertamenti svolti<\/strong> <strong>dalla commissione tecnica<\/strong>,<strong> istituita da Anas,<\/strong> sulle cause del cedimento e a valutare l&#8217;opportunit\u00e0 di procedere, sulla base di tali valutazioni, a promuovere un percorso di ripristino dell&#8217;opera&#8221;. &#8220;Sia chiaro &#8211; \u00e8 andata all&#8217;attacco Vittoria Baldino (M5s) che non \u00e8 la priorit\u00e0 di questa maggioranza riportare Longobucco fuori dall&#8217;isolamento&#8221;.<\/p>\n<h3><strong>Baldino (M5S): &#8220;non sapete cosa significa vivere nell&#8217;isolamento&#8221;<\/strong><\/h3>\n<p class=\"v1MsoNormal\">&#8220;Quando parlo di isolamento \u2013 attacca\u00a0<b>Baldino<\/b>\u00a0&#8211; mi riferisco al fatto che dopo il crollo della Sila Mare sono state miracolosamente riaperte al traffico e rese transitabili delle strade prima chiuse, perch\u00e9 a rischio frana. Il prezzo per uscire dall&#8217;isolamento \u00e8 rischiare la vita ogni qualvolta si percorre una strada per uscire dal paese. Quando parlo di isolamento mi riferisco al fatto che stiamo parlando di comunit\u00e0 non servite da servizi essenziali come ospedali e scuole. A tal proposito oltre il danno la beffa, durante la protesta dei cittadini \u00e8 giunta una nota dal ministero dell&#8217;istruzione e del merito sancenti la chiusura di una delle due scuole di secondo grado che servivano la citt\u00e0. Mentre una comunit\u00e0 restava isolata il ministero invitava le famiglie, tra cui quella di due studenti disabili, ad iscrivere i figli presso altre scuole della provincia. O<strong>ggi ci venite a dire \u2013 rilancia\u00a0Baldino\u00a0&#8211; che non c&#8217;\u00e8 nessuna urgenza per rispristinare l&#8217;opera e togliere Longobucco dall&#8217;isolamento?<\/strong>&#8220;.<\/p>\n<p class=\"v1MsoNormal\">&#8220;Avete provato a vivere in un paese da cui non si pu\u00f2 uscire? Dove si vi prende un infarto siete morti perch\u00e9 l&#8217;ambulanza non potr\u00e0 mai arrivare in tempo? In Calabria se hai un figlio disabile sei lasciato da solo: perch\u00e9 lo Stato non ti aiuta e ti chiude anche la scuola. Non voglio essere complice dell&#8217;ennesima presa in giro della politica che in trent&#8217;anni ha usato la Calabria solo come urna elettorale per portare nelle istituzioni persone che il nome Longobucco non lo sanno neanche pronunciare&#8221; conclude con forza\u00a0<b>Baldino<\/b><strong>\u00a0rimandando cos\u00ec indietro l&#8217;invito del governo a riformulare l&#8217;ordine del giorno<\/strong>. Riformulazione che voleva fermarsi a monitorare gli esiti della commissione tecnica sulle cause del cedimento e sulla base di tali esiti valutare l&#8217;opportunit\u00e0 di promuovere un ripristino dell&#8217;opera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; No della Camera a un ordine del giorno di M5s al decreto sul ponte sullo Stretto che impegnava il governo &#8220;a prevedere con urgenza, anche con un decreto legge ad hoc alla messa in sicurezza&#8221; della zona del crollo del viadotto del Comune di Longobucco. Via libera, invece, a un odg della Lega [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202050,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-202048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202048"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202050"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}