{"id":202059,"date":"2023-05-16T18:15:38","date_gmt":"2023-05-16T16:15:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202059"},"modified":"2023-05-16T18:16:18","modified_gmt":"2023-05-16T16:16:18","slug":"san-marco-argentanocs-sfida-a-colpi-di-peperoncino-con-i-piatti-del-territorio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/san-marco-argentanocs-sfida-a-colpi-di-peperoncino-con-i-piatti-del-territorio\/","title":{"rendered":"San Marco Argentano, sfida tra studenti a colpi di peperoncino con i piatti del territorio"},"content":{"rendered":"<p>SAN MARCO ARGENTANO (CS) &#8211; Una sfida che nasconde diversi aspetti, quello relativo alla formazione e quello legato alla valorizzazione dei prodotti del territorio, in primis <strong>il peperoncino<\/strong>. E&#8217; quella che ha visto protagonisti i ragazzi dell\u2019<strong>Istituto d&#8217;istruzione superiore di San Marco Argentano<\/strong>, centro in provincia di Cosenza, chiaramente <strong>l\u2019indirizzo alberghiero<\/strong>, grazie al progetto <strong>&#8220;Piatto piccante&#8221;<\/strong>, realizzato dal <strong>Consorzio dei Produttori del Peperoncino di Calabria<\/strong> in collaborazione con lo stesso istituto scolastico della citt\u00e0 normanna.<\/p>\n<p>Una vera e propria competizione con gli studenti delle ultime tre classi che hanno preparato <strong>piatti a base di peperoncino<\/strong> con una giuria che ha decretato il vincitore.<\/p>\n<p>Una giornata che si \u00e8 sviluppata in due fasi: quella pratica in cucina con i ragazzi, guidati dai docenti, a preparare i piatti da presentare alla giuria; quella di approfondimento nel corso della quale sono stati sviluppati <strong>temi legati alle peculiarit\u00e0 del territorio<\/strong>, ai prodotti ed a anche quelli che possono essere <strong>sbocchi lavorativi per gli studenti<\/strong>.<\/p>\n<div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>SAN MARCO ARGENTANO (CS) &#8211; Una sfida che nasconde diversi aspetti, quello relativo alla formazione e quello legato alla valorizzazione dei prodotti del territorio, in primis il peperoncino. E&#8217; quella che ha visto protagonisti i ragazzi dell\u2019Istituto d&#8217;istruzione superiore di San Marco Argentano, centro in provincia di Cosenza, chiaramente l\u2019indirizzo alberghiero, grazie al progetto &#8220;Piatto [&hellip;]<\/p>\n","protected":false},"author":65,"featured_media":202062,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[135],"class_list":["post-202059","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-provincia","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202059","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202059"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202059\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202062"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202059"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202059"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202059"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}