{"id":202189,"date":"2023-05-20T20:45:07","date_gmt":"2023-05-20T18:45:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202189"},"modified":"2023-05-20T20:46:10","modified_gmt":"2023-05-20T18:46:10","slug":"allunical-arriva-la-robotsumo-sfida-tra-robot-autonomi-progettati-dagli-studenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/allunical-arriva-la-robotsumo-sfida-tra-robot-autonomi-progettati-dagli-studenti\/","title":{"rendered":"All&#8217;Unical arriva la &#8216;Robotsumo&#8217;: sfida tra robot autonomi progettati dagli studenti"},"content":{"rendered":"<p>RENDE (CS) &#8211; <strong>All&#8217;Unical arriva la &#8216;Robotsumo&#8217;,<\/strong> evento organizzato dal corso di studio in ingegneria meccanica afferente al Dipartimento di Ingegneria Meccanica, Energetica, e Gestionale (DIMEG). Si tratta di una <strong>sfida tra robot autonomi,<\/strong> progettati da studenti di ingegneria, sponsorizzato dal DIMEG, presso il <strong>Teatro Auditorium Unical (TAU) il giorno 30 maggio 2023 alle ore 19:00<\/strong>, in piazza Vermicelli all\u2019estremit\u00e0 nord del Campus di Arcavacata.<\/p>\n<h3><strong>La &#8216;Robotsumo&#8217;: sfida tra robot autonomi<\/strong><\/h3>\n<p>La competizione, organizzata dai professori Giuseppe Carbone, Luigi Bruno, Maurizio Muzzupappa, Fabio Bruno e Domenico Mundo, con il prezioso contributo dei tutor Stefano Rodin\u00f2, Francesco Lago ed Elio Matteo Curcio, nonch\u00e9 dalle realt\u00e0 aziendali del territorio che hanno sponsorizzato il progetto, \u00e8 un&#8217;opportunit\u00e0 straordinaria per le <strong>squadre di ingegneri dei corsi di lauree triennale e magistrale in ingegneria meccanica<\/strong> per mettersi alla prova e sviluppare le proprie competenze attraverso la metodologia \u201clearning by doing\u201d. I robot autonomi progettati e realizzati dagli studenti, divisi in squadre,<strong> si sfideranno sul Dohy\u014d come dei veri lottatori di sumo!<\/strong><\/p>\n<p><strong>Da quest\u2019anno la competizione si apre anche alle scuole superiori,<\/strong> per favorire la sinergia tra istituti superiori e mondo accademico. Ci\u00f2 che rende ancora pi\u00f9 entusiasmante questa competizione \u00e8 l&#8217;atmosfera di divertimento e apprendimento, che incoraggia gli studenti a mettere in pratica le proprie conoscenze.<\/p>\n<p>La competizione, nata lo scorso anno, consiste in un<strong> girone all\u2019italiana<\/strong> per ogni categoria, in cui le diverse squadre si sfidano a duello uno contro l\u2019altro. I team verranno valutati sia sulla base dello sviluppo tecnico del proprio combattente, attraverso una breve presentazione per ogni squadra, sia sulla strategia di gioco sviluppata, determinante per l\u2019esito dei duelli.<\/p>\n<p>I robot vengono sviluppati interamente dagli studenti partendo dalla progettazione meccanica, che ne definisce forma e caratteristiche, alle componenti hardware e software, che ne completa il DNA, con la <strong>progettazione di algoritmi di gioco per duelli autonomi.<\/strong> L\u2019iniziativa completa il corso di studi integrando la soft skill del team working, creando un confronto costante tra studenti, docenti e tecnici.<\/p>\n<p><strong>Per partecipare all&#8217;evento come spettatore \u00e8 possibile prenotarsi al seguente link:<\/strong> <a href=\"https:\/\/qbot.it\/robotsumo\" rel=\"noopener\"><u>https:\/\/qbot.it\/robotsumo<\/u><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; All&#8217;Unical arriva la &#8216;Robotsumo&#8217;, evento organizzato dal corso di studio in ingegneria meccanica afferente al Dipartimento di Ingegneria Meccanica, Energetica, e Gestionale (DIMEG). Si tratta di una sfida tra robot autonomi, progettati da studenti di ingegneria, sponsorizzato dal DIMEG, presso il Teatro Auditorium Unical (TAU) il giorno 30 maggio 2023 alle ore [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202190,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-202189","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202189"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202189\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202190"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}