{"id":202254,"date":"2023-05-18T16:16:46","date_gmt":"2023-05-18T14:16:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202254"},"modified":"2023-05-18T16:16:46","modified_gmt":"2023-05-18T14:16:46","slug":"vittime-della-uno-bianca-parte-lesposto-dei-familiari-anche-dalla-calabria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/vittime-della-uno-bianca-parte-lesposto-dei-familiari-anche-dalla-calabria\/","title":{"rendered":"Vittime della &#8216;Uno bianca&#8217;: parte l&#8217;esposto dei familiari anche dalla Calabria"},"content":{"rendered":"<p>BOLOGNA &#8211; I delitti della famigerata &#8216;Uno bianca&#8217;, la banda che sconvolse l&#8217;Italia tra gli anni&#8217;80 e 90, ritornano sulla scena. Il 24 maggio alle 11.30 in Sala Borsa a Bologna \u00e8 prevista una conferenza stampa per presentare <strong>l&#8217;esposto depositato alla Procura nazionale antiterrorismo, alla Procura di Bologna e alla Procura di Reggio Calabria<\/strong> da parte di alcuni familiari delle vittime dei crimini della <strong>banda dell&#8217;Uno bianca, il gruppo criminale che tra il 1987 e il 1994 uccise 23 persone e ne fer\u00ec oltre 100<\/strong> tra Bologna, Romagna e Marche.<\/p>\n<p><strong>L&#8217;esposto mira a far riaprire le indagini su quei delitti,<\/strong> &#8220;nella convinzione di coloro che lo hanno redatto che la storia della banda si iscrivesse nella strategia terroristica e eversiva che ha insanguinato il nostro Paese per un quarto di secolo. L&#8217;esposto sar\u00e0 accompagnato da una nota di presentazione dell&#8217;avvocato Alessandro Gamberini difensore dei familiari, che dar\u00e0 conto del suo contenuto e sar\u00e0 resa pubblica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOLOGNA &#8211; I delitti della famigerata &#8216;Uno bianca&#8217;, la banda che sconvolse l&#8217;Italia tra gli anni&#8217;80 e 90, ritornano sulla scena. Il 24 maggio alle 11.30 in Sala Borsa a Bologna \u00e8 prevista una conferenza stampa per presentare l&#8217;esposto depositato alla Procura nazionale antiterrorismo, alla Procura di Bologna e alla Procura di Reggio Calabria da [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,16],"tags":[19],"class_list":["post-202254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202254"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202255"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}