{"id":202262,"date":"2023-05-18T17:52:58","date_gmt":"2023-05-18T15:52:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202262"},"modified":"2023-05-18T20:27:13","modified_gmt":"2023-05-18T18:27:13","slug":"a-tropea-un-nuovo-crollo-massi-giu-dal-costone-allinterno-della-grotta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/a-tropea-un-nuovo-crollo-massi-giu-dal-costone-allinterno-della-grotta\/","title":{"rendered":"A Tropea un nuovo crollo: massi gi\u00f9 dal costone all&#8217;interno della grotta"},"content":{"rendered":"<p><strong>TROPEA (VV) &#8211; Ancora un altro crollo a Tropea, in provincia di Vibo Valentia. Il nuovo cedimento si \u00e8 registrato all\u2019interno della grotta a Santa Maria dell\u2019Isola.<\/strong> Una frana che segue quella dello <strong><a href=\"https:\/\/quicosenza.it\/news\/calabria\/tropea-crollata-parte-del-costone-dellisola-a-picco-sul-mare\" target=\"_blank\" rel=\"noopener\">scorso 7 aprile, <\/a><\/strong>quando un grande costone roccioso cedette cadendo a picco sul mare. Oggi pomeriggio la frana ha interessato un punto non lontano da quello verificatosi la volta scorsa Per fortuna per\u00f2 non si sono registrati danni e soprattutto il crollo non ha coinvolto persone.<\/p>\n<p>L\u2019area dove si \u00e8 verificato il crollo, al momento, \u00e8 delimitata da spago e transenne, essendo <strong>interdetta da un\u2019ordinanza emessa dal sindaco di Tropea Giovanni Macr\u00ec<\/strong> per via dei cedimenti precedenti che rendono la zona pericolosa. Sul posto sono sopraggiunte subito le forze dell\u2019ordine ed i tecnici comunali per valutare l\u2019entit\u00e0 del danno.<\/p>\n<h3><strong>Il sindaco: &#8220;crolli avvenuti oggi erano gi\u00e0 previsti&#8221;<\/strong><\/h3>\n<p>&#8220;Messa in sicurezza di Santa Maria dell\u2019Isola, non hanno mai conosciuto e non conoscono soste le iniziative in tutte le direzioni e le attivit\u00e0 diverse, continue e costanti studiate e messe in campo dall\u2019Amministrazione Comunale sin dalle prime ore successive al crollo del 7 aprile scorso per accelerare e garantire la complessiva messa in sicurezza dell\u2019intero costone&#8221;.<\/p>\n<p>\u00c8 quanto dichiara il Sindaco Giovanni Macr\u00ec riferendo di un primo <strong>sopralluogo da parte dei tecnici incaricat<\/strong>i, a seguito di due ulteriori crolli verificatisi qualche ora fa nell\u2019area pi\u00f9 critica del sito.<\/p>\n<p><strong>&#8220;Questi ultimi crolli \u2013 continua \u2013 sono avvenuti all\u2019interno di un\u2019area di cantiere, chiusa al pubblico<\/strong> e gi\u00e0 da luned\u00ec scorso (15 maggio) transennata in modo adeguato e del tutto diverso da come purtroppo riferito in talune, solite mistificazioni giornalistiche.<\/p>\n<p><strong>Quelli accaduti oggi \u2013 precisa il Sindaco \u2013 erano crolli gi\u00e0 previsti<\/strong>. Anzi \u2013 chiarisce \u2013 proprio le parti cadute avrebbero dovuto essere oggetto di disgaggio, in quanto a rischio distacco imminente.<\/p>\n<p>Era stato tutto gi\u00e0 programmato negli interventi di somma urgenza per come compiutamente esposto nel corso della proficua riunione in Prefettura dell\u20198 maggio scorso, fortemente voluta dal Prefetto, tra tutte le rappresentanze istituzionali competenti e coinvolte, dalla Regione Calabria alla Sovraintendenza regionale, dalla Provincia alla Protezione Civile all\u2019Autorit\u00e0 di Bacino; riunione proficua \u2013 precisa il Primo Cittadino \u2013 svoltasi nella totale trasparenza e condivisione di metodi ed obiettivi, ovvero il contrario del silenzio tombale, del muro di gomma e delle improbabili <strong>pressioni lobbistiche inventate<\/strong> \u2013 scandisce \u2013 dai <strong>disinformatori seriali.<\/strong><\/p>\n<p>Il Primo Cittadino coglie l\u2019occasione per ribadire che sempre nei giorni scorsi sono partiti, nelle more di altri auspicati interventi e finanziamenti, le azioni di messa in sicurezza della corona dell\u2019Isola, per garantire il sito dalla forza e dai rischi delle mareggiate; interventi predisposti e finanziati direttamente dal Comune \u2013 spiega \u2013 nel quadro sempre e comunque del confronto e della concertazione permanente tra tutti gli enti e soggetti coinvolti e competenti.<\/p>\n<p>Parallelamente, nella giornata di domani (venerd\u00ec 19 maggio)<strong> partiranno anche i lavori di somma urgenza<\/strong> sulle parti gravemente compromesse per evitare pericoli imminenti.<\/p>\n<p><strong>FASE 2.<\/strong> \u2013 L\u2019Amministrazione Comunale sta anche lavorando per la successiva riapertura della sia della spiaggia che della grotta per renderle utilizzabili nel minore tempo possibile, nel rispetto sia della bellezza del sito, icona della Calabria e del Sud Italia nel mondo sia, soprattutto della sicurezza ed incolumit\u00e0 di tutti i suoi numerosissimi fruitori, in tutti i mesi dell\u2019anno.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TROPEA (VV) &#8211; Ancora un altro crollo a Tropea, in provincia di Vibo Valentia. Il nuovo cedimento si \u00e8 registrato all\u2019interno della grotta a Santa Maria dell\u2019Isola. Una frana che segue quella dello scorso 7 aprile, quando un grande costone roccioso cedette cadendo a picco sul mare. Oggi pomeriggio la frana ha interessato un punto [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202263,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-202262","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202262"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202262\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202263"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}