{"id":202666,"date":"2023-05-24T15:30:58","date_gmt":"2023-05-24T13:30:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202666"},"modified":"2023-05-24T15:00:12","modified_gmt":"2023-05-24T13:00:12","slug":"occhiuto-viadotto-crollato-non-aveva-fondamenta-le-norme-non-lo-prevedevano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/occhiuto-viadotto-crollato-non-aveva-fondamenta-le-norme-non-lo-prevedevano\/","title":{"rendered":"Occhiuto: &#8216;viadotto crollato non aveva fondamenta. Le norme non lo prevedevano&#8217;"},"content":{"rendered":"<p>LONGOBUCCO(CS)- Il viadotto <strong>&#8220;Ortiano 2&#8221; situato lungo la strada statale 177 Dir a Longobucco, in provincia di Cosenza<\/strong>, un cui tratto \u00e8 crollato il 3 maggio scorso in prossimit\u00e0 del pilone posto nell&#8217;alveo del fiume Trionto, &#8220;non aveva l&#8217;ancoraggio di 20 metri sotto il terreno, praticamente non aveva fondamenta&#8221;. Lo ha detto il presidente della regione Calabria Roberto Occhiuto.<\/p>\n<p>&#8220;Ho fatto una verifica con gli uffici regionali &#8211; ha detto Occhiuto &#8211;<strong> perch\u00e9 era un ponte recente costruito soltanto 9 anni prima<\/strong>. La cosa assurda \u00e8 che nella normativa del tempo, e probabilmente anche in quella attuale, non \u00e8 previsto che i ponti con i piloni negli alvei, debbano avere necessariamente questo ancoraggio di 20 metri. <strong>E&#8217; una cosa assurda e dimostra la scarsa attenzione che in questo Paese c&#8217;\u00e8 stata sul tema della sicurezza delle opere pubbliche<\/strong> e anche sul tema della messa in sicurezza del territorio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LONGOBUCCO(CS)- Il viadotto &#8220;Ortiano 2&#8221; situato lungo la strada statale 177 Dir a Longobucco, in provincia di Cosenza, un cui tratto \u00e8 crollato il 3 maggio scorso in prossimit\u00e0 del pilone posto nell&#8217;alveo del fiume Trionto, &#8220;non aveva l&#8217;ancoraggio di 20 metri sotto il terreno, praticamente non aveva fondamenta&#8221;. Lo ha detto il presidente della [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":201183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-202666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202666"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/201183"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}