{"id":202678,"date":"2023-05-24T17:39:38","date_gmt":"2023-05-24T15:39:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202678"},"modified":"2023-05-24T17:39:38","modified_gmt":"2023-05-24T15:39:38","slug":"citta-unica-senza-referendum-la-regione-smentisce-false-dichiarazioni-di-caruso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/citta-unica-senza-referendum-la-regione-smentisce-false-dichiarazioni-di-caruso\/","title":{"rendered":"Citt\u00e0 unica senza referendum? La Regione smentisce: \u00abfalse dichiarazioni di Caruso\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; \u201cLa modifica alla legge regionale approvata luned\u00ec scorso a Palazzo Campanella non cambia l\u2019iter legislativo e referendario sulla fusione dei comuni. Anzi, lo perfeziona senza snaturare il valore referendario che \u00e8 consultivo da dettami Costituzionali e non reso tale dal Consiglio Regionale come qualcuno sostiene. \u00c8 doveroso tornare sull\u2019argomento e <strong>smentire con forza e chiarezza le false dichiarazioni del <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/caruso-a-difesa-dei-cosentini-cosenza-non-si-inchina-al-centro-destra-che-vorrebbe-cancellarla\" target=\"_blank\" rel=\"noopener\">Sindaco di Cosenza Franz Caruso<\/a><\/strong>, nella speranza che le sue parole siano dettate da una distratta lettura del testo. Lo invitiamo, nel rispetto istituzionale e professionista forense ad approfondire l\u2019argomento senza confondere i cittadini\u201d a dichiararlo <strong>i consiglieri regionali firmatari della proposta di legge sulla fusione dei comuni di Cosenza, Rende e Castrolibero<\/strong>.<\/p>\n<p>\u201cNei principi fondamentali della costituzione e del testo unico delle leggi sull&#8217;ordinamento degli enti locali spetta al consiglio regionale guidare il processo di fusione dei comuni. Ci\u00f2 precisato e perfezionato <strong>nel testo approvato in Consiglio Regionale, lascia sempre e comunque alla volont\u00e0 popolare l\u2019ultimo passaggio<\/strong>. Ci venga chiarito, nella piena considerazione dei cittadini, senza creare confusione, chi \u00e8 a favore della Citt\u00e0 Unica.<\/p>\n<p>Alle Amministrazioni che guardano al benessere del territorio la libert\u00e0 di emettere delibere di fusione, scrutare in prospettiva futura nell\u2019interesse dei cittadini alle macro aree. \u00c8 paradossale altres\u00ec che, consiglieri comunali spinti da qualunquismo e dichiarazioni spot, affermino che con l\u2019intervento legislativo si sia cancellata la possibilit\u00e0 di fare un referendum; un passaggio obbligato che rimane e rimarr\u00e0 sempre nel potere delle comunit\u00e0.<\/p>\n<p>Ed \u00e8 ancor pi\u00f9 aberrante che rappresentanti istituzionali della citt\u00e0 parlino di fascismo e di ritorno ad un nefasto ventennio, sono solo offese gratuite e modaiole. A quanti invece cercano di innalzare barricate per rallentare una sempre pi\u00f9 marcata volont\u00e0 popolare verso la citt\u00e0 unica, il <strong>nostro invito \u00e8 di considerare i benefici per il territorio<\/strong>. Esortiamo anche i pi\u00f9 reticenti a partecipare al confronto nelle apposite commissioni quando le proposte di legge di fusione saranno concrete, testimoni di un processo di sviluppo per le nostre citt\u00e0 abbandonando per sempre l\u2019ingordigia del potere feudatario\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; \u201cLa modifica alla legge regionale approvata luned\u00ec scorso a Palazzo Campanella non cambia l\u2019iter legislativo e referendario sulla fusione dei comuni. Anzi, lo perfeziona senza snaturare il valore referendario che \u00e8 consultivo da dettami Costituzionali e non reso tale dal Consiglio Regionale come qualcuno sostiene. \u00c8 doveroso tornare sull\u2019argomento e smentire con forza [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202679,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-202678","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202678"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202678\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202679"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202678"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202678"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}