{"id":202705,"date":"2023-05-24T22:26:31","date_gmt":"2023-05-24T20:26:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202705"},"modified":"2023-05-25T00:16:14","modified_gmt":"2023-05-24T22:16:14","slug":"addio-a-tina-turner-regina-del-rockn-roll-muore-dopo-una-lunga-malattia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/addio-a-tina-turner-regina-del-rockn-roll-muore-dopo-una-lunga-malattia\/","title":{"rendered":"Addio a Tina Turner, regina del Rock&#8217;n Roll: muore dopo una lunga malattia"},"content":{"rendered":"<p>ZURIGO &#8211;\u00a0 <strong>Tina Turner \u00e8 morta all&#8217;et\u00e0 di 83 anni.<\/strong> Lo ha annunciato il suo portavoce, secondo quanto riporta Sky News.<\/p>\n<p>&#8220;Tina Turner, la Regina del Rock&#8217;n Roll, \u00e8 morta serenamente oggi <strong>all&#8217;et\u00e0 di 83 anni dopo una lunga malattia<\/strong> nella sua casa di K\u00fcsnacht vicino a Zurigo, in Svizzera. Con lei, il mondo perde una leggenda della musica e un modello&#8221;.<\/p>\n<p><strong>E&#8217; difficile trovare una storia come quella di Tina Turner, una vita talmente piena di eventi, drammi, tragedie, violenza, ascesa, caduta, rinascita da sembrare scritta da uno sceneggiatore.<\/strong><\/p>\n<p>E invece, Ann Mae Bullock, da Nutbush, Tennessee, infine cittadina svizzera, nata il 26 novembre del 1939 lascia il mondo dopo che un biopic, due musical, un paio di scioccanti autobiografie e tante canzoni indimenticabili, l&#8217;hanno da tempo consegnata alla leggenda.<\/p>\n<p>Tina \u00e8 stata una delle pi\u00f9 straordinarie performer mai apparse sui palcoscenici: Mick Jagger, tanto per fare un nome, che \u00e8 stato un suo amico fraterno, ha sempre ammesso di averle &#8220;rubato&#8221; il modo di stare in scena, ai tempi in cui i Rolling Stones erano cos\u00ec giovani da aprire i concerti di Ike &amp; Tina Turner. Le loro performance insieme, a cominciare da quella a Live Aid, sono pagine di storia. Un&#8217;icona di bellezza senza tempo, un fascino irresistibile, probabilmente le gambe pi\u00f9 belle della storia della musica (e non solo). Una voce inconfondibile, graffiante, immersa nella storia della black music ma perfetta per il pop da classifica, la capacit\u00e0 di resistere a un&#8217;esistenza che racchiude almeno tre vite, una naturale empatia sono gli elementi che ne hanno fatto una delle artiste di maggior successo di sempre.<\/p>\n<p><strong>Qualche anno fa, suo figlio Craig, avuto quasi adolescente da una relazione precedente a quella drammatica con Ike Turner, si \u00e8 suicidato a 59 anni.<\/strong> Ultimo colpo di una vita piena di drammi: Ike Turner, il marito con cui aveva messo su una band che \u00e8 stata determinante per la nascita del rock&#8217;n&#8217;roll e che l&#8217;ha resa famosa, si rivel\u00f2 un uomo violento, una sorta di schiavista domestico, che, nonostante il clamoroso successo di brani come &#8220;Proud Mary&#8221;, &#8220;Nutbush CityLimit s&#8221; e &#8220;River Deep Mountain High&#8221;, trasform\u00f2 la vita di Tina in un incubo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ZURIGO &#8211;\u00a0 Tina Turner \u00e8 morta all&#8217;et\u00e0 di 83 anni. Lo ha annunciato il suo portavoce, secondo quanto riporta Sky News. &#8220;Tina Turner, la Regina del Rock&#8217;n Roll, \u00e8 morta serenamente oggi all&#8217;et\u00e0 di 83 anni dopo una lunga malattia nella sua casa di K\u00fcsnacht vicino a Zurigo, in Svizzera. Con lei, il mondo perde [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[19],"class_list":["post-202705","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202705","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202705"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202705\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202708"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}