{"id":202741,"date":"2023-05-26T06:30:13","date_gmt":"2023-05-26T04:30:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=202741"},"modified":"2023-05-25T11:00:56","modified_gmt":"2023-05-25T09:00:56","slug":"da-domani-nel-cosentino-i-volontari-plastic-free-tornano-in-azione-per-lambiente","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/da-domani-nel-cosentino-i-volontari-plastic-free-tornano-in-azione-per-lambiente\/","title":{"rendered":"Da domani nel Cosentino i volontari Plastic free tornano in azione per l&#8217;ambiente"},"content":{"rendered":"<p>COSENZA &#8211; Dopo aver liberato<strong> la Calabria da 20.850 chilogrammi di plastica e rifiuti dispersi nell&#8217;ambiente in ben 23 appuntamenti di clean up tenutisi in contemporanea durante il weekend per la Terra lo scorso aprile<\/strong>, gli oltre 1.000 volontari calabresi di Plastic Free Onlus, l&#8217;organizzazione di volontariato impegnata dal 2019 nel contrastare l&#8217;inquinamento da plastica, tornano in azione. Da venerd\u00ec 26 a domenica 28 maggio, <strong>si terranno ben 11 appuntamenti in tutte le province per cavalcare l&#8217;onda positiva post evento nazionale e continuare a sensibilizzare e bonificare i singoli territori della Calabria.<\/strong> Si tratta del secondo evento regionale dopo quello realizzato nel 2021.<\/p>\n<p>&#8220;Sono molto entusiasta di questo rinnovato impegno in simultanea \u2013 dichiara Alberto Fio, referente regionale Calabria Plastic Free Onlus \u2013 Undici appuntamenti che rappresentano una ulteriore tappa verso un percorso di sensibilizzazione che ci sta dando molte soddisfazioni sia in termini di risposta da parte dei volontari sia da parte delle Istituzioni locali. Saremo in tutte le province della nostra regione. Invitiamo tutti coloro che hanno a cuore l&#8217;ambiente e la Calabria a farsi avanti: trascorreremo ore all&#8217;aria aperta, operando con il sorriso per un territorio pi\u00f9 pulito&#8221;, conclude Fio (Plastic Free Onlus).<\/p>\n<p>Si parte venerd\u00ec 26 maggio da Casabona in provincia di Crotone. <strong>Sabato 27 al mattino a Melito di Porto Salvo (Reggio Calabria) e Zumpano (Cosenza) mentre nel pomeriggio alle 15 l&#8217;onda blu Plastic Free Onlus sar\u00e0 in azione a Parenti (Cosenza).<\/strong> Ben sette appuntamenti domenica 28: al mattino a Palmi (Reggio Calabria), San Giovanni in Fiore (Cosenza), Lamezia Terme (Catanzaro), San Pietro in Guarano (Cosenza) e Reggio Calabria. Nel pomeriggio, infine, Montepaone (Catanzaro) e Bianco (Reggio Calabria).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Dopo aver liberato la Calabria da 20.850 chilogrammi di plastica e rifiuti dispersi nell&#8217;ambiente in ben 23 appuntamenti di clean up tenutisi in contemporanea durante il weekend per la Terra lo scorso aprile, gli oltre 1.000 volontari calabresi di Plastic Free Onlus, l&#8217;organizzazione di volontariato impegnata dal 2019 nel contrastare l&#8217;inquinamento da plastica, [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":202749,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-202741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=202741"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/202741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202749"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=202741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=202741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=202741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}