{"id":203022,"date":"2023-05-29T20:10:07","date_gmt":"2023-05-29T18:10:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=203022"},"modified":"2023-05-30T06:41:20","modified_gmt":"2023-05-30T04:41:20","slug":"paola-dopo-danni-allauto-del-sindaco-vandalizzato-un-asilo-nido-comunale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/paola-dopo-danni-allauto-del-sindaco-vandalizzato-un-asilo-nido-comunale\/","title":{"rendered":"Paola, dopo i danni all&#8217;auto del sindaco vandalizzato un asilo nido comunale"},"content":{"rendered":"<div dir=\"auto\">PAOLA (CS) &#8211; <strong>Ignoti hanno vandalizzato nella notte l&#8217;asilo nido comunale a Paola,<\/strong> inaugurato di recente. Un escalation criminale nella citt\u00e0 di San Francesco che lascia sgomenti dopo le <strong><a href=\"https:\/\/quicosenza.it\/news\/provincia\/minacce-e-sfregi-allauto-del-sindaco-di-paola-andiamo-avanti-con-coraggio-e-legalita\" target=\"_blank\" rel=\"noopener\">minacce e i danneggiamenti<\/a> all&#8217;auto del sindaco<\/strong>, Giovanni Politano, nei giorni scorsi.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">&#8220;Si tratta di un gesto insensato che <strong>condanniamo con fermezza &#8211;<\/strong> dichiara in una nota <strong>l&#8217;amministrazione comunale<\/strong>. &#8211; Gli episodi\u00a0 sporadici ma da non sottovalutare &#8211; di vandalismo e di violenza impongono una seria riflessione. Una comunit\u00e0 sana e attiva come quella Paolana non pu\u00f2 fare i conti con accaduti simili&#8221;.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Esprime amarezza l&#8217;amministrazione comunale della citt\u00e0 di Paola in una nota stampa che cos\u00ec prosegue: &#8220;Siamo prontamente intervenuti, grazie al consigliere comunale Sandra Serpa e all&#8217;ing. Fabio Iaccino, all&#8217;Ing. Fabio Pavone che hanno costatato i danni. Ovviamente &#8211; sottolinea &#8211; auspischiamo che le forze dell&#8217;ordine &#8211; prontamente intervenute sul posto &#8211; <strong>possano fare luce sulla vicenda che non pu\u00f2 esser etichettata come una semplice bravata<\/strong>. Si tratta &#8211; invece &#8211; di un atto grave perpetrato ai danni del mondo della scuola&#8221;.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">La maggioranza del sindaco di Paola, Giovanni Politano conclude: &#8220;A tutte quelle persone che fanno parte della sfera del nido comunale, alle maestre, a tutto il personale dell&#8217;asilo nido, ai bambini e alla bambine, alle famiglie paolane<strong> la promessa di porre rimedio ai danni subiti nel minor tempo possibile<\/strong> e di riconsegnare alla citt\u00e0 un edificio pi\u00f9 bello e sicuro. La scuola, i bambini e l&#8217;istruzione prima di tutto&#8221;.<\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>PAOLA (CS) &#8211; Ignoti hanno vandalizzato nella notte l&#8217;asilo nido comunale a Paola, inaugurato di recente. Un escalation criminale nella citt\u00e0 di San Francesco che lascia sgomenti dopo le minacce e i danneggiamenti all&#8217;auto del sindaco, Giovanni Politano, nei giorni scorsi. &#8220;Si tratta di un gesto insensato che condanniamo con fermezza &#8211; dichiara in una [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":203032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-203022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=203022"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/203022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/203032"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=203022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=203022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=203022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}