{"id":20323,"date":"2013-03-28T11:32:57","date_gmt":"2013-03-28T10:32:57","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=20323"},"modified":"2023-01-17T13:18:07","modified_gmt":"2023-01-17T12:18:07","slug":"7690-sanita-guccione-e-lo-polito-incontrano-dg-asp","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/7690-sanita-guccione-e-lo-polito-incontrano-dg-asp\/","title":{"rendered":"Sanit\u00e0: Guccione e Lo Polito incontrano Dg Asp"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CASTROVILLARI (CS)<\/strong> &#8211; &nbsp;Il Consigliere regionale del Pd Carlo Guccione insieme al sindaco di Castrovillari Domenico Lo Polito, hanno incontrato ,questa<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">mattina, il Direttore Generale dell&#8217;Asp di Cosenza Gianfranco Scarpelli. Un comunicato, spiega che i due esponenti politici &#8220;hanno affrontato una serie di criticita&#8217; che si registrano presso il presidio ospedaliero &#8220;spoke&#8221; di Castrovillari, dove particolarmente critiche risultano essere le Unita&#8217; Operative del Pronto Soccorso, Ortopedia e Pneumologia per mancanza di medici, personale infermieristico e O.S.S. (Operatori Socio Sanitari). La situazione piu&#8217; grave riguarda, in particolare, &#8211; si legge &#8211; l&#8217;Unita&#8217; Operativa di Ortopedia e Traumatologia in cui, gia&#8217; da un anno, i posti-letto sono stati ridotti da 20 a 10 per gravi carenze di organico e dove la situazione ultimamente si e&#8217; ulteriormente aggravata a causa del pensionamento di un medico per cui, ad oggi, risultano essere in servizio solo tre medici: un direttore facente-funzioni, un dirigente medico a tempo determinato e un dirigente medico con contratto per 34 ore, mentre il fabbisogno sarebbe almeno di sette medici. Il rischio e&#8217; che il reparto venga chiuso da un momento all&#8217;altro&#8221;. Guccione e Lo Polito hanno chiesto, inoltre, al Direttore Generale Scarpelli &#8220;di intervenire immediatamente, al fine di scongiurare il ridimensionamento di questi importanti servizi ospedalieri&#8221;. Quest&#8217;ultimo, dal canto suo, ha informato i due rappresentanti istituzionali &#8220;di aver gia&#8217; piu&#8217; volte richiesto l&#8217;autorizzazione all&#8217;Ufficio del Commissario per l&#8217;attuazione del Piano di Rientro di emanare avvisi pubblici per l&#8217;assunzione temporanea di personale medico e di non aver ricevuto finora nessuna risposta in tal senso&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; &nbsp;Il Consigliere regionale del Pd Carlo Guccione insieme al sindaco di Castrovillari Domenico Lo Polito, hanno incontrato ,questa<\/p>\n","protected":false},"author":22,"featured_media":20324,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-20323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=20323"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/20323\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/20324"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=20323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=20323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=20323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}